{"id":18793,"date":"2021-10-19T11:49:13","date_gmt":"2021-10-19T11:49:13","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/udazkeneko-udaberria\/"},"modified":"2021-10-26T07:56:02","modified_gmt":"2021-10-26T07:56:02","slug":"udazkeneko-udaberria","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/udazkeneko-udaberria\/","title":{"rendered":"Oto\u00f1o primaveral"},"content":{"rendered":"<p>Hoy, a pesar de estar inmersos en el oto&ntilde;o y a las puertas de noviembre y del cambio horario, gozamos de un d&iacute;a primaveral. Si a eso unimos que los alumnos y alumnas han ganado nuevos espacios en el jolastoki y la posibilidad de recuperar el contacto con amigos y amigas de otras gelas, el ambiente que se respira tiende a la normalidad que tanto ansiamos. Y todo ello, nos renueva. &iexcl;C&oacute;mo no! Aurrera!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy, a pesar de estar inmersos en el oto&ntilde;o y a las puertas de noviembre y del cambio horario, gozamos de un d&iacute;a primaveral. Si a eso unimos que los alumnos y alumnas han ganado nuevos espacios en el jolastoki y la posibilidad de recuperar el contacto con amigos y amigas de otras gelas, el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18772,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[219],"tags":[202,184,192],"class_list":["post-18793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otras-actividades","tag-conocemos-de-cerca-a","tag-cosas-del-dia","tag-instalaciones"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/18793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=18793"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/18793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/18772"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=18793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=18793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=18793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}