{"id":19035,"date":"2021-06-25T10:41:00","date_gmt":"2021-06-25T10:41:00","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/udalekuetarako-prest\/"},"modified":"2021-10-26T08:04:58","modified_gmt":"2021-10-26T08:04:58","slug":"udalekuetarako-prest","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/udalekuetarako-prest\/","title":{"rendered":"\u00bfPreparada la maleta para el campamento?"},"content":{"rendered":"\r\n<p><strong>Solo dos d\u00edas y nuestro hijo-a estar\u00e1 rumbo a Lizarra a Egino<\/strong>. Aventura, amigos, autonom\u00eda, naturaleza\u2026 y muchas experiencias. Y <strong>\u00bfqu\u00e9 pasa con los aitas y amas? \u00bfQu\u00e9 supone esta aventura para nosotros y nosotras?<\/strong> Sigue leyendo y te compartimos algunas reflexiones.<\/p>\r\n<p><strong>En ocasiones, vivimos esta experiencia de forma dual<\/strong>.<\/p>\r\n<p>Por una parte, <strong>reconocemos que efectivamente ser\u00e1 una experiencia positiva<\/strong> para ellos y ellas <strong>y valoramos la oportunidad que supone para nosotros como padres y madres<\/strong>, para disfrutar de otros espacios que en el d\u00eda a d\u00eda escasean.<\/p>\r\n<p><strong>Pero de otra, nos invaden ciertos miedos y preocupaciones<\/strong>; m\u00e1s a\u00fan cuando se van de campamento por primera vez.<\/p>\r\n<p><strong>\u00bfTe ocurre? <\/strong><\/p>\r\n<p>En este sentido, <strong>queremos compartir contigo algunas reflexiones<\/strong>.<\/p>\r\n<ul>\r\n<li><strong>De un lado la necesidad de tener en cuenta y aceptar que nuestros hijos e hijas se hacen mayores y que es as\u00ed como debe ser <\/strong>adem\u00e1s, en la medida en que queremos que se desarrollen como personas y sean felices. Pero en cierta medida vivimos este proceso como una peque\u00f1a p\u00e9rdida. En este sentido <strong><a title=\"Mis hijos se van de campamento por primera vez Lauaxeta Ikastola\" href=\"https:\/\/www.trendencias.com\/familia-maternidad-y-ninos-1\/es-la-primera-vez-que-se-van-de-campamento-y-asi-lo-voy-a-superar\" target=\"_blank\" rel=\"noopener\">compartimos las reflexiones de una amatxu, con las que seguro te sentir\u00e1s identificada o identificado<\/a>.<\/strong><\/li>\r\n<li><strong>De otro lado todo lo que sacar\u00e1n en positivo gracias a esta experiencia<\/strong>. Como pista, te compartimos algunas <a title=\"Cosas que aprenden en un campamento\" href=\"https:\/\/www.planetamamy.com\/2019\/04\/beneficios-campamento-hijos.html\/\" target=\"_blank\" rel=\"noopener\">en el siguiente enlace.<\/a><\/li>\r\n<\/ul>\r\n<p>&nbsp;<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Solo dos d\u00edas y nuestro hijo-a estar\u00e1 rumbo a Lizarra a Egino. Aventura, amigos, autonom\u00eda, naturaleza\u2026 y muchas experiencias. Y \u00bfqu\u00e9 pasa con los aitas y amas? \u00bfQu\u00e9 supone esta aventura para nosotros y nosotras? Sigue leyendo y te compartimos algunas reflexiones.<\/p>\n","protected":false},"author":1,"featured_media":16706,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[221],"tags":[206,198,202,184,181,207,185],"class_list":["post-19035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-extraescolares-y-de-verano","tag-actividades-de-verano","tag-aprendiendo-de-los-ninos","tag-conocemos-de-cerca-a","tag-cosas-del-dia","tag-educacion","tag-futuro","tag-metodologias-y-tecnicas-educativas"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/19035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=19035"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/19035\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/16706"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=19035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=19035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=19035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}