{"id":19237,"date":"2021-09-27T09:52:49","date_gmt":"2021-09-27T09:52:49","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/asteburu-baterako-proposamena\/"},"modified":"2021-10-26T07:59:48","modified_gmt":"2021-10-26T07:59:48","slug":"asteburu-baterako-proposamena","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/asteburu-baterako-proposamena\/","title":{"rendered":"Una propuesta para un fin de semana"},"content":{"rendered":"<p>Respondiendo a vuestras peticiones en la encuesta, <strong>si tienes un hijo o hija de entre 4 y 12 a&ntilde;os, te ofrecemos un posible plan para el fin de semana del 16 de octubre: &ldquo;La caja de los juguetes&rdquo;, un cuento musical lleno de ternura que ofrece la ABAO en el Teatro Arriaga<\/strong>, y a un precio especial para los alumnos y alumnas de Lauaxeta.<\/p>\n<p>Si te gusta el plan, tan solo tienes que seguir leyendo.<\/p>\n<p>Como todos los cursos, en &eacute;ste tambi&eacute;n colaboraremos con ABAO en su programa did&aacute;ctico dirigido a crear afici&oacute;n a la m&uacute;sica entre los alumnos\/as.<\/p>\n<p>Al comienzo de esta temporada, nos han ofrecido, en calidad de familias de centro educativo colaborador, la posibilidad de asistir a las Sesiones familiares del pr&oacute;ximo mes, con precios especiales: todas las entradas de ni&ntilde;os y adultos, tendr&aacute;n el precio de ni&ntilde;o,11&euro; (formando un grupo m&iacute;nimo de 20 personas).<\/p>\n<p>El espect&aacute;culo &ldquo;La Caja de los Juguetes&rdquo; se ofrecer&aacute; en el Teatro Arriaga Antzokia, el d&iacute;a 16 de octubre en &uacute;nico pase a las 18:00 p.m. y el 17 de octubre, en sesi&oacute;n matinal a las 12:00 p.m y vespertina a las 18:00 p.m. Est&aacute; recomendado a partir de los 4 a&ntilde;os.<\/p>\n<p>En caso de estar interesados en asistir, os pedimos que cumpliment&eacute;is el formulario que se ha enviado por email a las familias desde 4 a&ntilde;os a Primaria, antes del d&iacute;a 30 de septiembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Respondiendo a vuestras peticiones en la encuesta, <strong>si tienes un hijo o hija de entre 4 y 12 a&ntilde;os, te ofrecemos un posible plan para el fin de semana del 16 de octubre: &ldquo;La caja de los juguetes&rdquo;, un cuento musical lleno de ternura que ofrece la ABAO en el Teatro Arriaga<\/strong>, y a un precio especial para los alumnos y alumnas de Lauaxeta.<\/p>\n<p>Si te gusta el plan, tan solo tienes que seguir leyendo.<\/p>\n","protected":false},"author":1,"featured_media":19241,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[221],"tags":[209,202,184,181,214,185],"class_list":["post-19237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-extraescolares-y-de-verano","tag-actividades-culturales","tag-conocemos-de-cerca-a","tag-cosas-del-dia","tag-educacion","tag-educacion-infantil","tag-metodologias-y-tecnicas-educativas"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/19237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=19237"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/19237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/19241"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=19237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=19237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=19237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}