{"id":21048,"date":"2021-11-10T15:17:20","date_gmt":"2021-11-10T15:17:20","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/atzerrian-ikastea-ere-aukera-bat-da\/"},"modified":"2021-11-10T15:18:20","modified_gmt":"2021-11-10T15:18:20","slug":"atzerrian-ikastea-ere-aukera-bat-da","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/atzerrian-ikastea-ere-aukera-bat-da\/","title":{"rendered":"Estudiar en el extranjero es otra opci\u00f3n"},"content":{"rendered":"<p><strong>Algunos alumnos-as se plantean la posibilidad de estudiar en el extranjero, ya sea un curso completo o parte de \u00e9l<\/strong>. Esta semana precisamente se ofreci\u00f3 una <strong>charla informativa a las familias que est\u00e1n barajando esta posibilidad<\/strong>. \u00bfQuieres saber m\u00e1s? Te lo contamos.<\/p>\n<p><strong>EEUU, Canad\u00e1, Irlanda, Nueva Zelanda o Reino Unido son algunas de las posibilidades<\/strong> que se plantean <strong>desde 1\u00ba de ESO hasta 1\u00ba de Bachiller y de la mano de EAS-VELE.<\/strong><\/p>\n<p>Para acceder a m\u00e1s informaci\u00f3n puedes pinchar en el siguiente <a href=\"https:\/\/www.lauaxeta.eus\/wp-content\/uploads\/2021\/09\/Ikastola_Lauaxeta_EAS-VELE_Folleto_An%CC%83o_Acade%CC%81mico_e_Integracio%CC%81n_2021-225.pdf\" target=\"_blank\" rel=\"noopener\">enlace<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Algunos alumnos-as se plantean la posibilidad de estudiar en el extranjero, ya sea un curso completo o parte de \u00e9l. Esta semana precisamente se ofreci\u00f3 una charla informativa a las familias que est\u00e1n barajando esta posibilidad. \u00bfQuieres saber m\u00e1s? Te lo contamos. EEUU, Canad\u00e1, Irlanda, Nueva Zelanda o Reino Unido son algunas de las posibilidades [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":21046,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[366],"class_list":["post-21048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-experiencias-europeas","tag-hizkuntzak-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/21048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=21048"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/21048\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/21046"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=21048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=21048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=21048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}