{"id":23980,"date":"2020-09-21T12:21:03","date_gmt":"2020-09-21T12:21:03","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/bakean-heziz\/"},"modified":"2021-12-03T12:22:05","modified_gmt":"2021-12-03T12:22:05","slug":"bakean-heziz","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/bakean-heziz\/","title":{"rendered":"Educar en paz"},"content":{"rendered":"<p><strong>Vivir en sociedad supone conjugar intereses propios y ajenos,<\/strong> convivir con personas que pueden pensar como uno-a mismo-a o no y <strong>saber respetar al que tenemos enfrente<\/strong>, aun cuando no sea como nosotros-as. Hoy, se conmemora precisamente el d&iacute;a internacional de la paz. Sigue leyendo.<\/p>\n<p>Con esa idea, te ofrecemos <strong>distintos <a title=\"Educar en paz\" href=\"https:\/\/www.educaciontrespuntocero.com\/recursos\/cortometrajes-paz\/?utm_source=feedburner&amp;utm_medium=email&amp;utm_campaign=Feed%3A+educaciontrespuntocero%2FyZXs+%28Revista+Educaci%C3%B3n+3.0%29\" target=\"_blank\" rel=\"noopener\">recursos que sirven de inspiraci&oacute;n y pueden favorecer reflexiones interesantes acerca de la paz<\/a><\/strong>.<\/p>\n<p>Igualmente, traemos a la memoria <strong>experiencias de cursos pasados llevados a cabo en Lauaxeta Ikastola, como el <a title=\"World Peace Game Lauaxeta Ikastola\" href=\"\/es\/juguemos-en-paz-creemos-paz\" target=\"_blank\" rel=\"noopener\">World Peace Game<\/a> o el <a title=\"Adi-Adian Lauaxeta Ikastola\" href=\"\/es\/educando-en-la-paz-en-lauaxeta-ikastola\" target=\"_blank\" rel=\"noopener\">programa Adi-Adian<\/a>.<\/strong><\/p>\n<p>Hezi daigun bakean. Aurrera!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vivir en sociedad supone conjugar intereses propios y ajenos, convivir con personas que pueden pensar como uno-a mismo-a o no y saber respetar al que tenemos enfrente, aun cuando no sea como nosotros-as. Hoy, se conmemora precisamente el d&iacute;a internacional de la paz. Sigue leyendo. Con esa idea, te ofrecemos distintos recursos que sirven de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23977,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[219],"tags":[209,202,184,181,190,207,185],"class_list":["post-23980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otras-actividades","tag-actividades-culturales","tag-conocemos-de-cerca-a","tag-cosas-del-dia","tag-educacion","tag-educacion-para-la-sociedad","tag-futuro","tag-metodologias-y-tecnicas-educativas"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/23980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=23980"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/23980\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/23977"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=23980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=23980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=23980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}