{"id":23988,"date":"2021-03-22T12:25:20","date_gmt":"2021-03-22T12:25:20","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/aniztasunak-aberasten-gaitu\/"},"modified":"2021-12-03T12:26:32","modified_gmt":"2021-12-03T12:26:32","slug":"aniztasunak-aberasten-gaitu","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/aniztasunak-aberasten-gaitu\/","title":{"rendered":"La diferencia nos enriquece"},"content":{"rendered":"<p><strong>Vivimos en una sociedad plural y diversa<\/strong>, donde personas con diferentes perfiles y culturas compartimos espacios de trabajo y vida cotidiana. <strong>En ocasiones, merece la pena parar y reflexionar sobre ciertas realidades y es lo que han hecho precisamente los alumnos y alumnas ganadores de Lauaxeta en esta edici&oacute;n de &ldquo;Cuentos para pensar&rdquo;, centrada en el racismo.<\/strong> &iquest;Quieres saber m&aacute;s?<\/p>\n<p>Sigue leyendo.<\/p>\n<p><strong>Se trata de historias creadas por Mikel, Kattalin, June, Aiala, Jon o Izaro, alumnos y alumnas de Primaria de Lauaxeta<\/strong>,&nbsp;<a title=\"Cuentos contra el racismo premiados y premiadas\" href=\"https:\/\/fairsaturday.org\/es\/cuentos-para-pensar-racismo\/#ganadores\" target=\"_blank\" rel=\"noopener\">premiados y premiadas en este certamen<\/a>&nbsp;y que nos llevan a hacer una profunda reflexi&oacute;n acerca del racismo. Historias que puedes conocer en el siguiente&nbsp;<a title=\"Cuentos contra el racismo Fair Saturday Lauaxeta Ikastola\" href=\"https:\/\/fairsaturday.org\/es\/cuentos-para-pensar\/#toggle-id-1\" target=\"_blank\" rel=\"noopener\">libro digital.<\/a><\/p>\n<p>Debemos tomar conciencia de lo importante que es educar a nuestros hijos\/as en un entorno sin racismo, sin que las diferencias nos conviertan en enemigos, m&aacute;s bien en amigos dentro de entornos de diversidad, por un futuro en el que &eacute;ste se erradique.<\/p>\n<p><strong><a title=\"Entrega de premios cuentos contra el racismo\" href=\"https:\/\/www.youtube.com\/watch?time_continue=923&amp;v=xwltbIuqsiE&amp;feature=emb_logo\" target=\"_blank\" rel=\"noopener\">La entrega de premios<\/a>&nbsp;tuvo lugar a finales julio y esta pasada semana se present&oacute; el libro digital, aprovechando el d&iacute;a internacional contra el racismo.<\/strong><\/p>\n<p>Zorionak eta aurrera!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vivimos en una sociedad plural y diversa, donde personas con diferentes perfiles y culturas compartimos espacios de trabajo y vida cotidiana. En ocasiones, merece la pena parar y reflexionar sobre ciertas realidades y es lo que han hecho precisamente los alumnos y alumnas ganadores de Lauaxeta en esta edici&oacute;n de &ldquo;Cuentos para pensar&rdquo;, centrada en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23985,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[236],"tags":[209,198,202,184,190,213,207,215,185,195,189],"class_list":["post-23988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-premios-y-reconocimientos","tag-actividades-culturales","tag-aprendiendo-de-los-ninos","tag-conocemos-de-cerca-a","tag-cosas-del-dia","tag-educacion-para-la-sociedad","tag-fair-saturday-es","tag-futuro","tag-ikasleen-hitzetan-es","tag-metodologias-y-tecnicas-educativas","tag-premios-y-reconocimientos","tag-solidaridad"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/23988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=23988"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/23988\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/23985"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=23988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=23988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=23988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}