{"id":24263,"date":"2017-11-07T15:11:44","date_gmt":"2017-11-07T15:11:44","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/efizientzia-energetikoaren-aldeko-neurriak\/"},"modified":"2021-12-09T15:13:31","modified_gmt":"2021-12-09T15:13:31","slug":"efizientzia-energetikoaren-aldeko-neurriak","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/efizientzia-energetikoaren-aldeko-neurriak\/","title":{"rendered":"Medidas para la eficiencia energ\u00e9tica"},"content":{"rendered":"<p>Toda la energ\u00eda que se emplea en Lauaxeta Ikastola proviene de fuentes renovables y es destacable <strong>las medidas que en los 5 \u00faltimos a\u00f1os, se han tomado en pro de la sostenibilidad y que han contribuido de forma notable a la reducci\u00f3n del coste asociado a la energ\u00eda<\/strong>. \u00a0Tanto es as\u00ed, que <strong>el coste actual del gas y electricidad, comparando con el de 5 a\u00f1os atr\u00e1s se ha reducido en un 47%.<\/strong> \u00bfQuieres conocer <strong>cu\u00e1les son las medidas que nos han llevado a tan considerable ahorro? <\/strong><\/p>\n<p>Sigue leyendo.<\/p>\n<p>Las medidas que hemos implantado son las siguientes:<\/p>\n<ul>\n<li><strong>Sustituci\u00f3n de todas las luminarias, pasando al sistema LED. <\/strong><\/li>\n<li><strong>Cambio de las ventanas<\/strong>. A\u00fan cuando no todas han sido renovadas, podemos decir que la gran mayor\u00eda lo est\u00e1n.<\/li>\n<li><strong>Mejora del sistema de calefacci\u00f3n<\/strong>: de cara a asegurar la temperatura necesaria para cada espacio, <strong>garantizando el punto de confort y equilibrando el consumo y el coste asociados, contamos con un sistema de calefacci\u00f3n controlado por wifi <\/strong>que nos permite gestionar la temperatura de los diferentes espacios.<\/li>\n<li><strong>En relaci\u00f3n a las instalaciones de la piscina<\/strong>: la piscina es uno de los espacios de mayor consumo energ\u00e9tico de la ikastola,<strong> puesto que el agua de la misma debe mantenerse a una temperatura determinada y por razones de salubridad, el 2,5% del agua total de la piscina debe reciclarse diariamente. En la actualidad, contamos con un sistema mediante el que se aprovecha el calor del agua renovada<\/strong> para templar el nuevo, ahorrando con ello de forma significativa la energ\u00eda consumida.<\/li>\n<li>M\u00e1s all\u00e1 de las medidas anteriores<strong>, se desarrollan m\u00faltiples campa\u00f1as con los propios alumnos y alumnas, con el objetivo de educarles en u consumo responsable y de recudir al mismo tiempo el consumo de energ\u00eda de la ikastola.<\/strong> En este sentido, se toman medidas como por ejemplo el sem\u00e1foro de los interruptores: una serie de pegatinas pegadas en los interruptores de la ikastola, de forma que cuando un espacio necesita de iluminaci\u00f3n extra, se enciende el interruptor de menos a m\u00e1s respetando los colores de cada tecla del interruptor \u00a0y activando m\u00e1s o menos luces seg\u00fan se necesite, haciendo un uso racional y eficiente de la luz.<\/li>\n<\/ul>\n<p><strong>Todas las medidas anteriores, han supuesto un ahorro considerable en el consumo energ\u00e9tico de la ikastola y por tanto del coste asociado al mismo. Pero m\u00e1s all\u00e1 de esto, se ha reducido el coste tambi\u00e9n mediante el cambio del contrato de suministro energ\u00e9tico:<\/strong><\/p>\n<ul>\n<li>De un lado, porque <strong>al reducirse el consumo, la potencia contratada es tambi\u00e9n inferior y y coste fijo que se paga por la misma inferior. <\/strong><\/li>\n<li>Y de otro lado, porque<strong> hemos hecho un gran esfuerzo por identificar y seleccionar la mejor opci\u00f3n entre la oferta existente en l mercado. <\/strong><\/li>\n<\/ul>\n<p><strong>Como consecuencia de todo lo anterior, el coste de luz y gas en la actualidad, comparado con el de hace 5 a\u00f1os es un<\/strong> <strong>47% menor lo que supone una diferencia de 67.531\u20actako<\/strong>.<\/p>\n<p>Cabe destacar, que en las decisiones tomadas, hemos contado con el asesoramiento de <a href=\"http:\/\/www.gese.es\/\" target=\"_blank\" rel=\"noopener\">GESE<\/a> gestores energ\u00e9ticos, de cara a analizar en cada momento la mejor opci\u00f3n para Lauaxeta Ikastola y que en lo que se refiere a las inversiones realizadas, hemos contado con la ayuda de <a href=\"http:\/\/www.eve.eus\/\" target=\"_blank\" rel=\"noopener\">EVE<\/a>, Ente Vasco de la Energ\u00eda. Es importante se\u00f1alar igualmente que t<strong>odas las inversiones mencionadas se encuentran totalmente amortizadas en la actualidad. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toda la energ\u00eda que se emplea en Lauaxeta Ikastola proviene de fuentes renovables y es destacable las medidas que en los 5 \u00faltimos a\u00f1os, se han tomado en pro de la sostenibilidad y que han contribuido de forma notable a la reducci\u00f3n del coste asociado a la energ\u00eda. \u00a0Tanto es as\u00ed, que el coste actual [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24260,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[223],"tags":[180,192],"class_list":["post-24263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ods-y-agenda-2030","tag-agenda-21-es","tag-instalaciones"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/24263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=24263"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/24263\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/24260"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=24263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=24263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=24263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}