{"id":25639,"date":"2022-01-31T11:19:38","date_gmt":"2022-01-31T11:19:38","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/bakean-heztea-2\/"},"modified":"2022-01-31T11:20:21","modified_gmt":"2022-01-31T11:20:21","slug":"bakean-heztea-2","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/bakean-heztea-2\/","title":{"rendered":"Educar en la paz"},"content":{"rendered":"<p>En una <strong>sociedad diversa<\/strong> es importante educar a nuestros hijos-as y alumnos-as haciendo <strong>que sean conscientes de la riqueza que aporta este aspecto y de lo importante que resulta respetar otras ideas, sean o no compartidas. Educar en la paz,<\/strong> en definitiva.<\/p>\n<p><strong>Es algo que se trabaja en el d\u00eda a d\u00eda<\/strong>, en los conflictos o situaciones que puedan darse en la convivencia <strong>y tambi\u00e9n se trabaja con din\u00e1micas como World Peace Game<\/strong>, el juego de rol en el que est\u00e1n inmersos-as algunos-as alumnos-as de ESO.<\/p>\n<p>\u00bfQuieres saber m\u00e1s? <a href=\"https:\/\/www.lauaxeta.eus\/es\/zerbait-hartzen-dozu-zoriontsu-izateko\/\" target=\"_blank\" rel=\"noopener\">Te invitamos a visitar el siguiente enlace<\/a> y a visualizar el video que encontrar\u00e1s m\u00e1s abajo.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una sociedad diversa es importante educar a nuestros hijos-as y alumnos-as haciendo que sean conscientes de la riqueza que aporta este aspecto y de lo importante que resulta respetar otras ideas, sean o no compartidas. Educar en la paz, en definitiva. Es algo que se trabaja en el d\u00eda a d\u00eda, en los conflictos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":24297,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/25639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=25639"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/25639\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/24297"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=25639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=25639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=25639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}