{"id":25887,"date":"2022-02-17T08:46:22","date_gmt":"2022-02-17T08:46:22","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/japoniera-irakats-dezaket-eta-balleta-ikasi-nahiko-nuke\/"},"modified":"2022-02-17T08:49:09","modified_gmt":"2022-02-17T08:49:09","slug":"japoniera-irakats-dezaket-eta-balleta-ikasi-nahiko-nuke","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/japoniera-irakats-dezaket-eta-balleta-ikasi-nahiko-nuke\/","title":{"rendered":"\u00abPuedo ense\u00f1ar japon\u00e9s\u2026 y me gustar\u00eda aprender ballet\u00bb"},"content":{"rendered":"<p><strong>\u00bfQu\u00e9 te parece la idea de poder aprender y ense\u00f1ar algo a tus amigos-as a cambio solamente del tiempo que cada uno dedic\u00e1is al otro-a?<\/strong><\/p>\n<p>Es la iniciativa que se ha puesto en marcha en <strong>Primaria<\/strong>, a la que han llamado <strong>Cooperativa de Intercambio de Tiempo Solidario<\/strong>.<\/p>\n<p>El objetivo:<\/p>\n<ul>\n<li>Demostrar que no siempre tiene que mediar el dinero para conseguir un servicio de valor a\u00f1adido.<\/li>\n<li>Aprender de los compa\u00f1eros-as.<\/li>\n<li>Darnos cuenta de que tambi\u00e9n sabemos cosas que pueden aportar valor a otros.<\/li>\n<\/ul>\n<p><strong>Pero qu\u00e9 mejor que escucharlo en sus propias palabras. Puedes hacerlo en el siguiente video.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 te parece la idea de poder aprender y ense\u00f1ar algo a tus amigos-as a cambio solamente del tiempo que cada uno dedic\u00e1is al otro-a? Es la iniciativa que se ha puesto en marcha en Primaria, a la que han llamado Cooperativa de Intercambio de Tiempo Solidario. El objetivo: Demostrar que no siempre tiene que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":25885,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[235],"tags":[458,459],"class_list":["post-25887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectos","tag-lh-es","tag-primaria-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/25887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=25887"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/25887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/25885"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=25887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=25887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=25887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}