{"id":25924,"date":"2022-02-17T09:31:14","date_gmt":"2022-02-17T09:31:14","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/anfitrioi-ona-gonbidatuak-gustura-egoteaz-arduratzen-da\/"},"modified":"2022-02-17T09:33:22","modified_gmt":"2022-02-17T09:33:22","slug":"anfitrioi-ona-gonbidatuak-gustura-egoteaz-arduratzen-da","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/anfitrioi-ona-gonbidatuak-gustura-egoteaz-arduratzen-da\/","title":{"rendered":"Un buen anfitri\u00f3n se encarga de que los invitados-as est\u00e9n a gusto"},"content":{"rendered":"<p>Y los m\u00e1s txikis de 5 a\u00f1os lo saben.\u00a0 Ayer se dedicaron a recopilar plantas, palos\u2026 para hacer m\u00e1s acogedor el espacio donde habitan los<a href=\"https:\/\/www.lauaxeta.eus\/es\/oraingoan-zapaburuekin-ikasiko-dugu\/\" target=\"_blank\" rel=\"noopener\"> zapaburus<\/a>. Eso s\u00ed, saben que ser\u00e1 algo transitorio, y que cuando se hagan un poco m\u00e1s mayores, se trasladar\u00e1n al estanque de Lauaxeta.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Y los m\u00e1s txikis de 5 a\u00f1os lo saben.\u00a0 Ayer se dedicaron a recopilar plantas, palos\u2026 para hacer m\u00e1s acogedor el espacio donde habitan los zapaburus. Eso s\u00ed, saben que ser\u00e1 algo transitorio, y que cuando se hagan un poco m\u00e1s mayores, se trasladar\u00e1n al estanque de Lauaxeta. &nbsp; &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":25916,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/25924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=25924"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/25924\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/25916"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=25924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=25924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=25924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}