{"id":26388,"date":"2022-03-07T14:14:24","date_gmt":"2022-03-07T14:14:24","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/body-positive-norberaren-onarpena-landuz-geure-gorputzetik-hasita\/"},"modified":"2022-03-07T14:16:40","modified_gmt":"2022-03-07T14:16:40","slug":"body-positive-norberaren-onarpena-landuz-geure-gorputzetik-hasita","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/body-positive-norberaren-onarpena-landuz-geure-gorputzetik-hasita\/","title":{"rendered":"Body positive, trabajando la autoaceptaci\u00f3n, a trav\u00e9s de nuestro cuerpo"},"content":{"rendered":"<p><strong>Si utilizas a menudo las redes sociales probablemente hayas escuchado acerca del movimiento Body positive<\/strong>, pero quiz\u00e1s no sepas exactamente de qu\u00e9 trata o que intenta revindicar.<\/p>\n<p><strong>El body positive es un t\u00e9rmino que ha nacido en Internet y ha sido adoptado como una especie de filosof\u00eda de pensamiento positivo, de amarse a s\u00ed mismo-a, empezando por nuestro cuerpo<\/strong>.<\/p>\n<p><strong>Se centra en abrazar la diversidad, en lugar de luchar por un \u201ccuerpo perfecto\u201d<\/strong> seg\u00fan lo decretado por la sociedad. Se trata de trabajar la autoaceptaci\u00f3n.<\/p>\n<p><strong><a href=\"https:\/\/www.lauaxeta.eus\/es\/nor-naiz-ni-dbhko-3-mailako-gazteei-zuzendutako-proiektu-berria\/\">En el marco del proyecto \u201c\u00bfQui\u00e9n soy yo?\u201d desarrollado en 3\u00ba de ESO en torno a la nuestra identidad<\/a><\/strong> en medio de todas las circunstancias y el contexto que rodea a <strong>los alumnos-as de 14-15 a\u00f1os, hemos decidido realizar tambi\u00e9n reflexiones en torno a este concepto de Body Positive<\/strong>, para trabajar tambi\u00e9n la aceptaci\u00f3n desde ese \u00e1mbito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si utilizas a menudo las redes sociales probablemente hayas escuchado acerca del movimiento Body positive, pero quiz\u00e1s no sepas exactamente de qu\u00e9 trata o que intenta revindicar. El body positive es un t\u00e9rmino que ha nacido en Internet y ha sido adoptado como una especie de filosof\u00eda de pensamiento positivo, de amarse a s\u00ed mismo-a, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":26384,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224,226,235],"tags":[454,455],"class_list":["post-26388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escuela-de-padres","category-mejora-e-innovacion","category-proyectos","tag-dbh-es","tag-eso-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/26388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=26388"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/26388\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/26384"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=26388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=26388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=26388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}