{"id":26565,"date":"2022-03-15T11:27:08","date_gmt":"2022-03-15T11:27:08","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/adingabeak-eta-gerrak-zer-deritzote-nola-hitz-egin-horri-buruz\/"},"modified":"2022-03-15T11:27:48","modified_gmt":"2022-03-15T11:27:48","slug":"adingabeak-eta-gerrak-zer-deritzote-nola-hitz-egin-horri-buruz","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/adingabeak-eta-gerrak-zer-deritzote-nola-hitz-egin-horri-buruz\/","title":{"rendered":"Los menores y la guerra: \u00bfqu\u00e9 opinan? \u00bfc\u00f3mo hablar de ello?"},"content":{"rendered":"<p>\u00bfPor qu\u00e9 hay una guerra? \u00bfQu\u00e9 va a pasar? \u00bfVa a llegar aqu\u00ed? <strong>Los menores se hacen muchas preguntas ante la situaci\u00f3n que se est\u00e1 viviendo en Ucrania.<\/strong><\/p>\n<p><strong>Euskal Telebista ha querido acercarse concretamente a los adolescentes y ha emitido hoy en el programa Euskadi hoy unas breves palabras de algunos-as alumnos-as de Lauaxeta<\/strong>. Puedes verlo en el video que encontrar\u00e1s a continuaci\u00f3n.<\/p>\n<p>M\u00e1s all\u00e1 de lo anterior, <strong>al igual que en otros \u00e1mbitos de la vida, conviene hablar tambi\u00e9n de este tema con ellos-as, adaptando la conversaci\u00f3n a su edad<\/strong> y su capacidad para comprender lo que sucede.<\/p>\n<p>En este sentido, te dejamos con un art\u00edculo de inter\u00e9s.<\/p>\n<p><a href=\"https:\/\/www.educaciontrespuntocero.com\/noticias\/hablar-menores-guerra\/?utm_source=feedburner&amp;utm_medium=email\" target=\"_blank\" rel=\"noopener\">C\u00f3mo hablar con los menores sobre la guerra<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfPor qu\u00e9 hay una guerra? \u00bfQu\u00e9 va a pasar? \u00bfVa a llegar aqu\u00ed? Los menores se hacen muchas preguntas ante la situaci\u00f3n que se est\u00e1 viviendo en Ucrania. Euskal Telebista ha querido acercarse concretamente a los adolescentes y ha emitido hoy en el programa Euskadi hoy unas breves palabras de algunos-as alumnos-as de Lauaxeta. Puedes [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":26179,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224,231],"tags":[514,515,454,516,455,517],"class_list":["post-26565","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escuela-de-padres","category-lauaxeta-en-los-medios","tag-bakea-es","tag-convivencia-es","tag-dbh-es","tag-elkarbizitza-es","tag-eso-es","tag-paz-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/26565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=26565"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/26565\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/26179"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=26565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=26565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=26565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}