{"id":27632,"date":"2022-04-06T12:45:59","date_gmt":"2022-04-06T12:45:59","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/finlandiatik-lauaxetara-ekintzailetza-esperientzien-bila\/"},"modified":"2022-04-06T12:47:26","modified_gmt":"2022-04-06T12:47:26","slug":"finlandiatik-lauaxetara-ekintzailetza-esperientzien-bila","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/finlandiatik-lauaxetara-ekintzailetza-esperientzien-bila\/","title":{"rendered":"Profesores de Finlandia visitan Lauaxeta, para conocer experiencias de emprendimiento"},"content":{"rendered":"<p><strong>Carola Holmlund y Jan Nedergard, profesores de la <a href=\"https:\/\/vamia.fi\/\" target=\"_blank\" rel=\"noopener\">Escuela Vamia<\/a> de Finlandia y premio nacional al profesor emprendedor del a\u00f1o, visitaron ayer Lauaxeta, para conocer diferentes experiencias de emprendizaje. <\/strong><\/p>\n<p>En su viaje <strong>han querido acercarse a conocer otros centros educativos de profesores que a su vez obtuvieron el premio al profesor emprendedor<\/strong>, como es el caso de Egoitz Etxeandia de Lauaxeta.<\/p>\n<p><strong>En su agenda, tienen varias paradas<\/strong>, y han tenido ocasi\u00f3n de acercarse a: <a href=\"https:\/\/www.mondragon.edu\/es\/grado-liderazgo-emprendedor-innovacion\" target=\"_blank\" rel=\"noopener\">Grado en Liderazgo Emprendedor de Mondragoi Unibertsitatea (LEINN)<\/a>, <a href=\"https:\/\/bbfaktoria.mondragon.edu\/es\/inicio\" target=\"_blank\" rel=\"noopener\">Bilbao Berrikuntza Faktoria<\/a>, o la nueva plataforma de <a href=\"https:\/\/www.eroskicorporativo.es\/eroski-inaugura-la-automatizacion-de-su-plataforma-logistica-en-elorrio-unica-en-europa\" target=\"_blank\" rel=\"noopener\">Log\u00edstica de Eroski<\/a><\/p>\n<p>Posteriormente se acercar\u00e1n a otros centros educativos de Francia e Italia.<\/p>\n<p><strong>En Lauaxeta, han podido conocer entre otros proyectos como: Funghi Thinking, MaskBags, o el Proyecto emprendizaje que se desarrolla con los alumnos-as de Bachillerato.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carola Holmlund y Jan Nedergard, profesores de la Escuela Vamia de Finlandia y premio nacional al profesor emprendedor del a\u00f1o, visitaron ayer Lauaxeta, para conocer diferentes experiencias de emprendizaje. En su viaje han querido acercarse a conocer otros centros educativos de profesores que a su vez obtuvieron el premio al profesor emprendedor, como es el [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":27630,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[225,236],"tags":[],"class_list":["post-27632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conferencias-e-intervenciones","category-premios-y-reconocimientos"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/27632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=27632"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/27632\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/27630"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=27632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=27632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=27632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}