{"id":28572,"date":"2022-05-17T13:38:42","date_gmt":"2022-05-17T13:38:42","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/lauaxetako-bi-ikasle-olinpiada-matematikoetan\/"},"modified":"2022-05-17T13:39:24","modified_gmt":"2022-05-17T13:39:24","slug":"lauaxetako-bi-ikasle-olinpiada-matematikoetan","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/lauaxetako-bi-ikasle-olinpiada-matematikoetan\/","title":{"rendered":"Dos alumnas de Lauaxeta en las olimpiadas matem\u00e1ticas"},"content":{"rendered":"<p>Tras una primera fase realizada en cada centro educativo, <strong>Ane Bilbao Olabarri y Ane Iglesias Mi\u00f1o han participado en la \u00faltima fase de las olimpiadas matem\u00e1ticas de Euskadi<\/strong>. Aurrera, neskak!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras una primera fase realizada en cada centro educativo, Ane Bilbao Olabarri y Ane Iglesias Mi\u00f1o han participado en la \u00faltima fase de las olimpiadas matem\u00e1ticas de Euskadi. Aurrera, neskak! &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":28570,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[236],"tags":[454,455],"class_list":["post-28572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-premios-y-reconocimientos","tag-dbh-es","tag-eso-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/28572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=28572"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/28572\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/28570"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=28572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=28572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=28572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}