{"id":28625,"date":"2022-05-17T13:52:56","date_gmt":"2022-05-17T13:52:56","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/agur-bat-gure-ia-ia-ikasle-ohi-berriei\/"},"modified":"2022-05-17T13:53:36","modified_gmt":"2022-05-17T13:53:36","slug":"agur-bat-gure-ia-ia-ikasle-ohi-berriei","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/agur-bat-gure-ia-ia-ikasle-ohi-berriei\/","title":{"rendered":"Un abrazo a nuestros casi ex-alumnos y ex-alumnas"},"content":{"rendered":"<p>Estos d\u00edas nos acordamos especialmente de vosotros y vosotras. <strong>Pr\u00e1cticamente el curso escolar ha finalizado para vosotros-as, pero os queda por delante la prueba de acceso a la universidad. Aurrera!<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estos d\u00edas nos acordamos especialmente de vosotros y vosotras. Pr\u00e1cticamente el curso escolar ha finalizado para vosotros-as, pero os queda por delante la prueba de acceso a la universidad. Aurrera! &nbsp; &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":28578,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[227,219],"tags":[371,370],"class_list":["post-28625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antiguos-alumnos-as","category-otras-actividades","tag-bachillerato","tag-batxilergoa-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/28625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=28625"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/28625\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/28578"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=28625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=28625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=28625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}