{"id":29865,"date":"2022-06-20T08:39:16","date_gmt":"2022-06-20T08:39:16","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/osasun-mentalaren-aldeko-ipuinak-sormena-eta-kontzientziazioa-sarituak\/"},"modified":"2022-06-20T08:41:41","modified_gmt":"2022-06-20T08:41:41","slug":"osasun-mentalaren-aldeko-ipuinak-sormena-eta-kontzientziazioa-sarituak","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/osasun-mentalaren-aldeko-ipuinak-sormena-eta-kontzientziazioa-sarituak\/","title":{"rendered":"Cuentos por la salud mental, \u00a1creatividad y concienciaci\u00f3n premiadas!"},"content":{"rendered":"<p>La iniciativa\u00a0 <strong>\u201cCuentos para pensar\u201d de la Fundaci\u00f3n Fair Saturday consiste en un concurso literario dirigido ni\u00f1os\/as y j\u00f3venes con el objetivo de fomentar la reflexi\u00f3n acerca de diferentes problem\u00e1ticas sociales a trav\u00e9s de la creatividad literaria. En esta nueva edici\u00f3n, \u00a1algunos alumnos y alumnas de Lauaxeta Ikastola han resultado premiados-as!<\/strong><\/p>\n<p>En <strong>esta nueva edici\u00f3n, se les ha invitado a reflexionar acerca de la salud mental<\/strong>, con el objetivo de provocar reflexiones individuales y colectivas que rompan con los tab\u00faes y estigmas que se generan alrededor de ella.<\/p>\n<p><strong>Varios alumnos y alumnas de Lauaxeta Ikastola han participado y algunos-as han sido merecedores de un premio, concretamente Jon Ayarzaguena, en la categor\u00eda de 5\u00ba-6\u00ba Primaria, con su cuento \u201cEska dezagun laguntza\u201d y Nerea Lazpita Oar-arteta, que ha obtenido una menci\u00f3n especial, por su trabajo \u201cNire gorputza ez da nire aukera\u201d.<\/strong><\/p>\n<p>Si quieres profundizar y tener m\u00e1s informaci\u00f3n, puedes hacerlo en el <a href=\"https:\/\/fairsaturday.org\/es\/cuentos-para-pensar\/?utm_medium=email&amp;_hsmi=216588842&amp;_hsenc=p2ANqtz-_Fk-WyniXYY8x2UV2y8-mRaOQ0xwS09ntfDrPiKzEt_1OGqULzHQKB644qt0u1n5OJK-XLYGPBfEC-U7NzQ7XNNpnKQxBSx3MIo56yc4A3\" target=\"_blank\" rel=\"noopener\">siguiente enlace.<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La iniciativa\u00a0 \u201cCuentos para pensar\u201d de la Fundaci\u00f3n Fair Saturday consiste en un concurso literario dirigido ni\u00f1os\/as y j\u00f3venes con el objetivo de fomentar la reflexi\u00f3n acerca de diferentes problem\u00e1ticas sociales a trav\u00e9s de la creatividad literaria. En esta nueva edici\u00f3n, \u00a1algunos alumnos y alumnas de Lauaxeta Ikastola han resultado premiados-as! En esta nueva edici\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":29863,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[236,1],"tags":[458,459],"class_list":["post-29865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-premios-y-reconocimientos","category-sin-categorizar","tag-lh-es","tag-primaria-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/29865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=29865"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/29865\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/29863"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=29865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=29865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=29865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}