{"id":30165,"date":"2022-06-28T08:52:16","date_gmt":"2022-06-28T08:52:16","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/eta-azkenik-elkartu-ginen\/"},"modified":"2022-06-28T08:55:28","modified_gmt":"2022-06-28T08:55:28","slug":"eta-azkenik-elkartu-ginen","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/eta-azkenik-elkartu-ginen\/","title":{"rendered":"Y por fin volvimos a encontrarnos"},"content":{"rendered":"<p><strong>Este pasado s\u00e1bado\u00a0 nos reencontramos por fin con muchos ex alumnos y ex alumnas.<\/strong> Ten\u00edamos una cita pendiente especialmente con las dos \u00faltimas promociones, ya que debido a la situaci\u00f3n de estos dos \u00faltimos a\u00f1os no pudimos celebrar vuestra Agur jaia, pero la invitaci\u00f3n se extendi\u00f3 m\u00e1s all\u00e1 y pudimos reencontrarnos tambi\u00e9n con alumnos-as que nos dejaron hace bastantes a\u00f1os m\u00e1s. Fue un placer volver a juntarnos. Besarkada bana!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este pasado s\u00e1bado\u00a0 nos reencontramos por fin con muchos ex alumnos y ex alumnas. Ten\u00edamos una cita pendiente especialmente con las dos \u00faltimas promociones, ya que debido a la situaci\u00f3n de estos dos \u00faltimos a\u00f1os no pudimos celebrar vuestra Agur jaia, pero la invitaci\u00f3n se extendi\u00f3 m\u00e1s all\u00e1 y pudimos reencontrarnos tambi\u00e9n con alumnos-as que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":30126,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[227,1],"tags":[],"class_list":["post-30165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antiguos-alumnos-as","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/30165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=30165"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/30165\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/30126"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=30165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=30165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=30165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}