{"id":34371,"date":"2022-10-27T14:01:08","date_gmt":"2022-10-27T14:01:08","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=34371"},"modified":"2022-10-27T14:01:08","modified_gmt":"2022-10-27T14:01:08","slug":"moda-solidaridad-e-igualdad","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/moda-solidaridad-e-igualdad\/","title":{"rendered":"Moda, solidaridad e igualdad"},"content":{"rendered":"<p><strong>\u00bfQu\u00e9 relaci\u00f3n tienen estos tres aspectos? Gracias a una iniciativa de Haregin, el grupo de alumnos-as que trabaja en favor de la igualdad en Lauaxeta, lo tienen. Y es que han organizado un mercadillo de ropa de 2\u00aa mano, con el objetivo de destinar lo recaudado, a una ONG, pero m\u00e1s concretamente a un proyecto de empoderamiento de la mujer en Senegal.<\/strong><\/p>\n<p>Nos dirigimos a vosotros y <strong>vosotras para poner en vuestro conocimiento una nueva iniciativa solidaria, de la mano de Haregin taldea, el grupo de alumnos-as de Lauaxeta que trabaja a favor de la igualdad<\/strong>. Se trata de un<strong> mercadillo de ropa de segunda mano dirigido a edades comprendidas entre ESO y Bachillerato, <\/strong>con una causa muy coherente a la actividad que desarrolla este grupo, puesto que<strong> lo recaudado ser\u00e1 destinado a un proyecto de empoderamiento de la mujer en Senegal, de la ONG<\/strong> Euleuk.<\/p>\n<p>Ma\u00f1ana y el s\u00e1bado de 11:00 a 13:00, a\u00fan estar\u00e1n en el espacio Laia gunea de Lauaxeta.<\/p>\n<p>M\u00e1s informaci\u00f3n: <a href=\"https:\/\/euleuk.org\/es\/proyectos\/huertas-comunitarias-en-el-poblado-de-soussane-sarene\/\" target=\"_blank\" rel=\"noopener\">https:\/\/euleuk.org\/es\/proyectos\/huertas-comunitarias-en-el-poblado-de-soussane-sarene\/<\/a>).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 relaci\u00f3n tienen estos tres aspectos? Gracias a una iniciativa de Haregin, el grupo de alumnos-as que trabaja en favor de la igualdad en Lauaxeta, lo tienen. Y es que han organizado un mercadillo de ropa de 2\u00aa mano, con el objetivo de destinar lo recaudado, a una ONG, pero m\u00e1s concretamente a un proyecto [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":34390,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[302,220,229,226,223,217],"tags":[371,370,454,455],"class_list":["post-34371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alianzas","category-eventos-y-celebraciones","category-gestion","category-mejora-e-innovacion","category-ods-y-agenda-2030","category-solidaridad","tag-bachillerato","tag-batxilergoa-es","tag-dbh-es","tag-eso-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/34371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=34371"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/34371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/34390"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=34371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=34371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=34371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}