{"id":34866,"date":"2022-11-11T08:44:45","date_gmt":"2022-11-11T08:44:45","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=34866"},"modified":"2022-11-11T08:44:45","modified_gmt":"2022-11-11T08:44:45","slug":"que-aprenden-los-ninos-as-cuando-estan-en-la-naturaleza","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/que-aprenden-los-ninos-as-cuando-estan-en-la-naturaleza\/","title":{"rendered":"\u00bfQu\u00e9 aprenden los ni\u00f1os-as cuando est\u00e1n en la naturaleza?"},"content":{"rendered":"<p><strong>Aire puro, espacios abiertos, luz del sol, actividad f\u00edsica y alegr\u00eda.. suena bien, \u00bfno crees?<\/strong> Y es que la naturaleza reconforta el bienestar y equilibra psicol\u00f3gicamente.<\/p>\n<p>No hace falta grandes estudios que lo corroboren, pero <strong>a veces est\u00e1 bien que alguien nos lo recuerde. Mar\u00eda Montessori y otros profesionales del \u00e1mbito de la psicolog\u00eda y la educaci\u00f3n se encargan de ello, en el <a href=\"https:\/\/elpais-com.cdn.ampproject.org\/c\/s\/elpais.com\/mamas-papas\/familia\/2022-06-25\/que-aprenden-los-ninos-cuando-estan-en-la-naturaleza-y-por-que-la-necesitan-como-el-comer.html?outputType=amp\" target=\"_blank\" rel=\"noopener\">siguiente art\u00edculo.<\/a><\/strong><\/p>\n<p><strong>Mientras tanto, los alumnos-as de Lauaxeta, siempre que el tiempo nos lo permita seguir\u00e1n disfrutando de ello: aire puro, espacios abiertos, luz del sol, actividad f\u00edsica y \u00a1mucha alegr\u00eda! <\/strong>Asteburu on!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aire puro, espacios abiertos, luz del sol, actividad f\u00edsica y alegr\u00eda.. suena bien, \u00bfno crees? Y es que la naturaleza reconforta el bienestar y equilibra psicol\u00f3gicamente. No hace falta grandes estudios que lo corroboren, pero a veces est\u00e1 bien que alguien nos lo recuerde. Mar\u00eda Montessori y otros profesionales del \u00e1mbito de la psicolog\u00eda y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":34861,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[214,408],"class_list":["post-34866","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escuela-de-padres","tag-educacion-infantil","tag-hh-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/34866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=34866"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/34866\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/34861"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=34866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=34866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=34866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}