{"id":35533,"date":"2022-12-02T10:48:49","date_gmt":"2022-12-02T10:48:49","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=35533"},"modified":"2022-12-02T10:51:54","modified_gmt":"2022-12-02T10:51:54","slug":"y-hoy-por-fin-celebramos-el-dia-del-euskara","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/y-hoy-por-fin-celebramos-el-dia-del-euskara\/","title":{"rendered":"Y hoy, \u00a1por fin celebramos el d\u00eda del Euskara!"},"content":{"rendered":"<p>Manifiesto en favor del euskara, actividades diversas con alumnos-as de diferentes edades, bertsos a cargo de los propios alumnos-as, charla de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Jon_Maia\" target=\"_blank\" rel=\"noopener\">Jon Maia<\/a> e <a href=\"https:\/\/www.athletic-club.eus\/jugadores\/iraia-iturregi-sustatxa\" target=\"_blank\" rel=\"noopener\">Iraia Iturregi<\/a> y\u2026 \u00a1hasta un video sorpresa de los profesores-as de Infantil y Prmaria!<\/p>\n<p>Te dejamos con el video y con algunas fotos de la ma\u00f1ana, para que veas el ambiente que tenemos. Ondo izan!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Manifiesto en favor del euskara, actividades diversas con alumnos-as de diferentes edades, bertsos a cargo de los propios alumnos-as, charla de Jon Maia e Iraia Iturregi y\u2026 \u00a1hasta un video sorpresa de los profesores-as de Infantil y Prmaria! Te dejamos con el video y con algunas fotos de la ma\u00f1ana, para que veas el ambiente [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":35544,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[220],"tags":[201,408,434],"class_list":["post-35533","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos-y-celebraciones","tag-euskara-es","tag-hh-es","tag-infantil"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/35533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=35533"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/35533\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/35544"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=35533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=35533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=35533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}