{"id":36812,"date":"2023-01-09T15:08:56","date_gmt":"2023-01-09T15:08:56","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=36812"},"modified":"2023-01-09T15:08:56","modified_gmt":"2023-01-09T15:08:56","slug":"genero-identidad-y-orientacion-sexual-por-una-sociedad-mas-respetuosa","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/genero-identidad-y-orientacion-sexual-por-una-sociedad-mas-respetuosa\/","title":{"rendered":"G\u00e9nero, identidad y orientaci\u00f3n sexual. Por una sociedad m\u00e1s respetuosa"},"content":{"rendered":"<p>Los j\u00f3venes de 2\u00ba de ESO de Lauaxeta han desarrollado un proyecto interdisciplinar sobre g\u00e9nero, identidad y orientaci\u00f3n sexual. El objetivo de este proyecto:\u00a0<strong>concienciarles sobre la diversidad de g\u00e9neros, orientaciones e identidades.<\/strong>\u00a0Es decir, hacerles reflexionar sobre los diferentes g\u00e9neros, identidades no normativas de g\u00e9nero y orientaciones sexuales, para construir una sociedad m\u00e1s abierta y respetuosa, de la mano entre otros de Amestuz, Naizen, Mujeres con voz y Unetxea.<\/p>\n<p>En este marco,\u00a0<strong>se han desarrollado acciones de profundizaci\u00f3n en estos tres \u00e1mbitos<\/strong>:<\/p>\n<ul>\n<li><strong><u>Reflexionar sobre los roles de mujeres y hombres:\u00a0<\/u><\/strong>analizar las letras de las canciones actuales, re-imaginar los roles de los h\u00e9roes de los cuentos, trabajar la pel\u00edcula Billy Elliot\u2026<\/li>\n<li><strong><u>Reflexionar sobre otros g\u00e9neros<\/u><\/strong>: han recibido la conferencia de la organizaci\u00f3n Deseo, han utilizado el cortometraje \u201cun vestido nuevo\u201d para comprender y profundizar en la elaboraci\u00f3n del colectivo Trans, conocer y hablar mucho sobre los casos reales<\/li>\n<li><strong><u>Reflexionar sobre las m\u00faltiples orientaciones sexuales<\/u><\/strong>: reflexi\u00f3n a partir de un corto, leer y comentar noticias relacionadas con la LGTBIQ+\u2026<\/li>\n<\/ul>\n<p>Al final del proyecto han tomado un tema que han trabajado a lo largo de la unidad y han redactado un informe para defenderlo (para hacer un an\u00e1lisis de la realidad) y construir una campa\u00f1a publicitaria para presentarla.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los j\u00f3venes de 2\u00ba de ESO de Lauaxeta han desarrollado un proyecto interdisciplinar sobre g\u00e9nero, identidad y orientaci\u00f3n sexual. El objetivo de este proyecto:\u00a0concienciarles sobre la diversidad de g\u00e9neros, orientaciones e identidades.\u00a0Es decir, hacerles reflexionar sobre los diferentes g\u00e9neros, identidades no normativas de g\u00e9nero y orientaciones sexuales, para construir una sociedad m\u00e1s abierta y respetuosa, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":36813,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[235],"tags":[454,455],"class_list":["post-36812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectos","tag-dbh-es","tag-eso-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/36812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=36812"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/36812\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/36813"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=36812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=36812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=36812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}