{"id":37765,"date":"2023-01-25T09:02:41","date_gmt":"2023-01-25T09:02:41","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=37765"},"modified":"2023-01-25T09:02:41","modified_gmt":"2023-01-25T09:02:41","slug":"que-podemos-esperar-cuando-nos-aproximamos-a-la-adolescencia","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/que-podemos-esperar-cuando-nos-aproximamos-a-la-adolescencia\/","title":{"rendered":"\u00bfQu\u00e9 podemos esperar cuando nos aproximamos a la adolescencia?"},"content":{"rendered":"<p><strong>Todas las etapas de nuestros hijos e hijas suponen un reto<\/strong>, en la medida en que ellos y ellas van cambiando y superando distintos retos e incorporando nuevos aprendizajes a su vida. <strong>Pero si hay una etapa que en ocasiones tememos es la adolescencia. \u00bfQu\u00e9 esperar de ella? \u00bfC\u00f3mo acompa\u00f1ar a nuestros hijos-as en esta nueva etapa?<\/strong><\/p>\n<p><strong>Con la intenci\u00f3n de ofreceros algunas pistas, organizamos una sesi\u00f3n especial dirigida a familias con hijos-as de 6\u00ba de Primaria<\/strong>, de la mano de <a href=\"https:\/\/gac.com.es\/\">Albor Cosh.<\/a><\/p>\n<p><strong>En el<a href=\"https:\/\/youtu.be\/NBvryGpqKos\" target=\"_blank\" rel=\"noopener\"> siguiente enlace<\/a> encontrar\u00e1s un avance de la misma y <a href=\"https:\/\/www.lauaxeta.eus\/en\/famiia-eskola\/\" target=\"_blank\" rel=\"noopener\">en este otro enlace ver\u00e1s este y otros contenidos de la Escuela de familias. El acceso a esta formaci\u00f3n lo ver\u00e1s en el apartado de LH6.<\/a><\/strong><\/p>\n<p>Si eres familia de la ikastola y <strong>quieres visualizar toda la sesi\u00f3n, tan solo tienes que <a href=\"https:\/\/www.lauaxeta.eus\/eu\/ikasturteari-buruzko-informazioa\/\" target=\"_blank\" rel=\"noopener\">entrar en la parte privada de nuestra web <\/a><\/strong>y tendr\u00e1s acceso a ella, en la escuela de familias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todas las etapas de nuestros hijos e hijas suponen un reto, en la medida en que ellos y ellas van cambiando y superando distintos retos e incorporando nuevos aprendizajes a su vida. Pero si hay una etapa que en ocasiones tememos es la adolescencia. \u00bfQu\u00e9 esperar de ella? \u00bfC\u00f3mo acompa\u00f1ar a nuestros hijos-as en esta [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":28981,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-37765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/37765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=37765"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/37765\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/28981"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=37765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=37765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=37765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}