{"id":39578,"date":"2023-03-20T09:56:16","date_gmt":"2023-03-20T09:56:16","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=39578"},"modified":"2023-03-20T09:56:16","modified_gmt":"2023-03-20T09:56:16","slug":"3-alumnas-de-lauaxeta-se-llevan-el-primer-premio-un-reto-por-la-ciencia-de-sener","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/3-alumnas-de-lauaxeta-se-llevan-el-primer-premio-un-reto-por-la-ciencia-de-sener\/","title":{"rendered":"3 alumnas de Lauaxeta se llevan el primer premio \u201cUn reto por la ciencia\u201d de Sener"},"content":{"rendered":"<p><strong>M\u00f3nica Guti\u00e9rrez, Ane Iglesias e Irati Seij\u00f3, participar<\/strong><strong>on en el certamen<\/strong><strong> en\u00a0<a href=\"https:\/\/www.fundacion.sener\/formacion-e-investigacion\/un-reto-por-la-ciencia-2\/\" target=\"_blank\" rel=\"noopener\">\u201cUn reto por la ciencia\u201d de la Fundaci\u00f3n Sener<\/a>. Y lo han hecho tan bien que <\/strong><strong>\u00a1<\/strong><strong>han <\/strong><strong>obtenido el primer premio!<\/strong><\/p>\n<p>El trabajo desarrollado se llama \u201cSunny nights\u201d y consiste en un sistema de energ\u00eda solar para los robots Rober que pueden funcionar en noches de luna o en la cara oscura de esta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00f3nica Guti\u00e9rrez, Ane Iglesias e Irati Seij\u00f3, participaron en el certamen en\u00a0\u201cUn reto por la ciencia\u201d de la Fundaci\u00f3n Sener. Y lo han hecho tan bien que \u00a1han obtenido el primer premio! El trabajo desarrollado se llama \u201cSunny nights\u201d y consiste en un sistema de energ\u00eda solar para los robots Rober que pueden funcionar en [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":39579,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[236],"tags":[454,455],"class_list":["post-39578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-premios-y-reconocimientos","tag-dbh-es","tag-eso-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/39578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=39578"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/39578\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/39579"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=39578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=39578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=39578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}