{"id":39918,"date":"2023-04-24T08:57:33","date_gmt":"2023-04-24T08:57:33","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=39918"},"modified":"2023-04-24T08:57:33","modified_gmt":"2023-04-24T08:57:33","slug":"experimentos-y-ciencia-desde-casa","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/experimentos-y-ciencia-desde-casa\/","title":{"rendered":"Experimentos y ciencia desde casa"},"content":{"rendered":"<p>Muchas veces hacemos referencia en este blog a la importancia de <strong>pasar tiempo de calidad en familia<\/strong>. Hacer excursiones, visitas a museos, manualidades y, por qu\u00e9 no, experimentos. Esta <strong>semana os traemos varios experimentos que los alumnos-as de bachillerato desarrollaron con los de Infantil en la ikastola con motivo del <a href=\"https:\/\/www.lauaxeta.eus\/es\/la-ciencia-es-divertida\/\">d\u00eda de la ciencia celebrado en Lauaxeta.<\/a><\/strong><\/p>\n<p>Se trata de experimentos que han decidido recopilar los propios-as alumnos-as y que pod\u00e9is llevar a cabo con vuestros\/as hijos\/as a trav\u00e9s de los cuales pueden aprender, sin darse cuenta, nociones b\u00e1sicas en estas materias.<\/p>\n<p><a href=\"https:\/\/www.lauaxeta.eus\/wp-content\/uploads\/2023\/04\/LXT-Esperimentuen-liburuxka.pdf\">Puedes consultar el peque\u00f1o libro de experimentos en este enlace.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muchas veces hacemos referencia en este blog a la importancia de pasar tiempo de calidad en familia. Hacer excursiones, visitas a museos, manualidades y, por qu\u00e9 no, experimentos. Esta semana os traemos varios experimentos que los alumnos-as de bachillerato desarrollaron con los de Infantil en la ikastola con motivo del d\u00eda de la ciencia celebrado [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":39919,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224,235],"tags":[408,434],"class_list":["post-39918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escuela-de-padres","category-proyectos","tag-hh-es","tag-infantil"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/39918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=39918"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/39918\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/39919"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=39918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=39918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=39918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}