{"id":40241,"date":"2023-05-15T08:57:40","date_gmt":"2023-05-15T08:57:40","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=40241"},"modified":"2023-05-15T08:57:58","modified_gmt":"2023-05-15T08:57:58","slug":"iniciativas-para-pensar-sobre-el-mundo-y-mejorarlo","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/iniciativas-para-pensar-sobre-el-mundo-y-mejorarlo\/","title":{"rendered":"Iniciativas para pensar sobre el mundo y mejorarlo"},"content":{"rendered":"<p><strong>Los alumnos-as pueden cambiar la sociedad de la que forman parte y mejorarla. Ideas y creatividad no les faltan y todo cambio comienza con una reflexi\u00f3n profunda acerca de la situaci\u00f3n actual, del punto de partida.<\/strong><\/p>\n<p><strong>Es lo que tienen en com\u00fan precisamente las dos iniciativas de las que en esta ocasi\u00f3n nos hablan los alumnos-as de LauHaixetara Irratia:<\/strong><\/p>\n<p><strong><a href=\"https:\/\/fairsaturday.org\/es\/pentsatzeko-ipuinak\/\" target=\"_blank\" rel=\"noopener\">De un lado la iniciativa cuentos para pensar, de Fair Saturday<\/a>,<\/strong> que invita precisamente a los alumnos-as a pensar y escribir acerca de una tem\u00e1tica de actualidad. En esta edici\u00f3n ser\u00e1 sobre las redes sociales y el plazo para quienes se animen se extiende hasta el pr\u00f3ximo 22 de mayo.<\/p>\n<p><strong><a href=\"https:\/\/onetwothink.com\/eskola-arteko-sormen-lehiaketa-sapere-aude\/\" target=\"_blank\" rel=\"noopener\">Y de otro la iniciativa Sapere Aude<\/a><\/strong>, que retaba a los alumnos-as a proponer inventos que cambien el mundo, ya sea desde el punto de vista del medioambiente, la igualdad o el bienestar social y en el que dos proyectos de Lauaxeta Ikastola resultaron seleccionados y premiados: <strong>\u201cHerri ekologikoa\u201d de 3\u00ba de Primaria y \u201cWalki-robot\u201d de 2\u00ba de Primaria.<\/strong><\/p>\n<p><strong>Sobre ambos temas conversan en esta ocasi\u00f3n los alumnos-as de LauHaixetara Irratia. <a href=\"https:\/\/go.ivoox.com\/rf\/108082286\" target=\"_blank\" rel=\"noopener\">Te invitamos a escucharlos en este enlace.<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los alumnos-as pueden cambiar la sociedad de la que forman parte y mejorarla. Ideas y creatividad no les faltan y todo cambio comienza con una reflexi\u00f3n profunda acerca de la situaci\u00f3n actual, del punto de partida. Es lo que tienen en com\u00fan precisamente las dos iniciativas de las que en esta ocasi\u00f3n nos hablan los [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":40191,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[236],"tags":[458,459],"class_list":["post-40241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-premios-y-reconocimientos","tag-lh-es","tag-primaria-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/40241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=40241"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/40241\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/40191"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=40241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=40241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=40241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}