{"id":40434,"date":"2023-05-22T12:27:34","date_gmt":"2023-05-22T12:27:34","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=40434"},"modified":"2023-05-22T12:27:34","modified_gmt":"2023-05-22T12:27:34","slug":"dysfood-tres-alumnas-ofrecen-soluciones-para-personas-con-disfagia","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/dysfood-tres-alumnas-ofrecen-soluciones-para-personas-con-disfagia\/","title":{"rendered":"Dysfood: tres alumnas ofrecen soluciones para personas con disfagia"},"content":{"rendered":"<p><strong>\u00bfSabes que 1 de cada 17 personas sufre o sufrir\u00e1 alg\u00fan tipo de disfagia a lo largo de su vida?<\/strong> Pero \u00bfqu\u00e9 es la disfagia? <strong>Se trata de la dificultad de degluci\u00f3n o para tragar. Significa tener problemas con el descenso de alimentos o l\u00edquidos por la garganta, habitualmente por causa de un ictus que la persona ha sufrido o por la presencia de tumores<\/strong>.<\/p>\n<p>En estas situaciones, el afectado-a se ve obligado-a a <strong>comer los alimentos con determinada consistencia y su preparaci\u00f3n conlleva un tiempo extra<\/strong>.<\/p>\n<p><strong>Carla Urrutia Magnard, Leire Gallego Miranda y Luc\u00eda San Sebasti\u00e1n Alfageme no solo han empatizado con estas personas sino que han puesto su creatividad, competencias y ganas a su servicio y han creado Dysfood, la empresa que ofrece comida tradicional ya preparada para personas con disfagia<\/strong>.<\/p>\n<p>La empresa ofrece platos de nuestro d\u00eda a d\u00eda con 3 tipos de consistencia, apta para los afectados-as y listos para su consumo inmediato.<\/p>\n<p>La idea <strong>surgi\u00f3 ante el reto que Lauaxeta Ikastola les plante\u00f3 de identificar una necesidad de su entorno y darle respuesta creando una empresa para ello. Tras darle forma a su idea la presentaron en la feria de emprendimiento de Lauaxeta Ikastola y posteriormente lo han hecho en la feria <a href=\"https:\/\/www.expofoodtech.com\/\" target=\"_blank\" rel=\"noopener\">Food 4 future celebrada recientemente en el BEC.<\/a><\/strong><\/p>\n<p>Si quieres profundizar en lo que ofrecen te dejamos el enlace directo a <a href=\"https:\/\/dysfoodes.wixsite.com\/dysfood?fbclid=PAAaYjPOny7rJlglF1VPj-DWVi4BjKzTrguslNqYWfu63lQ2ia7zgzO3-17vE\">su p\u00e1gina web<\/a>, as\u00ed como a su <a href=\"https:\/\/www.instagram.com\/dysfood_es\/?igshid=MzRlODBiNWFlZA%3D%3D\" target=\"_blank\" rel=\"noopener\">cuenta de Instagram<\/a> y su <a href=\"https:\/\/www.youtube.com\/watch?app=desktop&amp;fbclid=PAAaajQhf06qkNobkkv8SCsRjoQfr7LUVtm1dJKnEjaulVcACgVja8dvJxtB8&amp;v=4jDmFwUDDmk&amp;feature=youtu.be\" target=\"_blank\" rel=\"noopener\">Elevator Pitch.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfSabes que 1 de cada 17 personas sufre o sufrir\u00e1 alg\u00fan tipo de disfagia a lo largo de su vida? Pero \u00bfqu\u00e9 es la disfagia? Se trata de la dificultad de degluci\u00f3n o para tragar. Significa tener problemas con el descenso de alimentos o l\u00edquidos por la garganta, habitualmente por causa de un ictus que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":40428,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[236],"tags":[371,370],"class_list":["post-40434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-premios-y-reconocimientos","tag-bachillerato","tag-batxilergoa-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/40434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=40434"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/40434\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/40428"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=40434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=40434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=40434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}