{"id":41183,"date":"2023-06-28T10:33:52","date_gmt":"2023-06-28T10:33:52","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=41183"},"modified":"2023-06-28T10:33:52","modified_gmt":"2023-06-28T10:33:52","slug":"vacaciones-amigos-aficiones-udalekuak","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/vacaciones-amigos-aficiones-udalekuak\/","title":{"rendered":"Vacaciones, amigos, aficiones&#8230; udalekuak!"},"content":{"rendered":"<p>Vacaciones, amigos, aficiones&#8230; udalekuak!<\/p>\n<p>Suena bien \u00bfverdad? Aunque a la mayor\u00eda de padres y madres a\u00fan nos toca esperar un poco para disfrutar de las nuestras, nuestros hijos e hijas ya est\u00e1n de vacaciones. Y <strong>aquellos y aquellas que han optado por las propuestas de Lauaxeta, est\u00e1n la disfrutando a tope. \u00bfQuieres verlo?<\/strong><\/p>\n<p><strong>Las udaleku irekiak de Lauaxeta ya est\u00e1n en marcha: actividades diversas seg\u00fan la edad<\/strong>: manualidades, paseos, surf\u2026 puedes echar un vistazo en las fotos o\u00a0<a title=\"Udaleku irekiak Lauaxeta Ikastola\" href=\"https:\/\/54.37.122.150\/es\/disfrutrando-del-verano-como-se-merecen\" target=\"_blank\" rel=\"noopener\">acceder a informaci\u00f3n m\u00e1s detallada en el siguiente enlace.<\/a><\/p>\n<p><strong>Y\u2026 los que se han animado a ir a Lizarra y Egino, \u00a1tan solo ten\u00e9is que echar un vistazo a sus cuentas de Instagram!<\/strong> En este enlace pod\u00e9is ver la cuenta de <a title=\"Instagram Lizarra Lauaxeta Ikastola\" href=\"https:\/\/www.instagram.com\/lizarraudalekua_lauaxetaikasto\/\" target=\"_blank\" rel=\"noopener\">Instagram de Lizarra<\/a>\u00a0y en este\u00a0<a title=\"Instagram Egino Lauaxeta Ikastola\" href=\"https:\/\/www.instagram.com\/eginoudalekua_lauaxetaikasto\/\" target=\"_blank\" rel=\"noopener\">otro a la de Egino<\/a>.<\/p>\n<p>Ondo pasa!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plan ona, ezta? Guraso gehienek pixka bat itxaron behar dogu oraindik gure oporrez gozatzeko, baina, <strong>gure seme-alabak oporretan dagoz. Lauaxetaren proposamenen alde egin dabenek, gogotik gozatzen ari dira<\/strong>. Ikusi nahi dozu?<\/p>\n","protected":false},"author":3,"featured_media":41172,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[206,202,184,193,181,679,190,680,681,194,682,192,683,185],"class_list":["post-41183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-actividades-de-verano","tag-conocemos-de-cerca-a","tag-cosas-del-dia","tag-deporte","tag-educacion","tag-educacion-2-es","tag-educacion-para-la-sociedad","tag-educacion-para-la-sociedad-2-es","tag-extraescolares-2-es","tag-extraescolares","tag-instalaciones-2-es","tag-instalaciones","tag-metodologias-y-tecnicas-educativas-2-es","tag-metodologias-y-tecnicas-educativas"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/41183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=41183"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/41183\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/41172"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=41183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=41183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=41183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}