{"id":41926,"date":"2023-09-14T07:46:57","date_gmt":"2023-09-14T07:46:57","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=41926"},"modified":"2023-09-14T07:47:35","modified_gmt":"2023-09-14T07:47:35","slug":"disfrutando-de-nuevos-espacios","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/disfrutando-de-nuevos-espacios\/","title":{"rendered":"\u00a1Disfrutando de nuevos espacios!"},"content":{"rendered":"<p><strong>Este curso los-as m\u00e1s peque\u00f1os-as han podido estrenar y disfrutar sus nuevas aulas. <\/strong>Dentro de las obras realizadas, <strong>hemos adaptado los espacios al proyecto pedag\u00f3gico de Educaci\u00f3n Infantil, consiguiendo un entorno m\u00e1s c\u00f3modo y transparente y conectando las aulas directamente con <a href=\"https:\/\/www.lauaxeta.eus\/es\/ikaspark-estrenando-y-disfrutando-de-nuevos-espacios\/\">la zona de juego de Ikaspark<\/a>.<br \/>\n<\/strong>Estas obras se han desarrollado dentro del Plan Lauaxeta Campus y adem\u00e1s de las citadas <a href=\"https:\/\/www.lauaxeta.eus\/wp-content\/uploads\/2023\/09\/LAUAXETA-IKASTOLA-Lauaxeta-Campus-2023-2024-vdef.pdf\">se han desarrollado las siguientes<\/a>:<br \/>\n\u2022 Renovaci\u00f3n de acceso a secretar\u00eda y recepci\u00f3n<br \/>\n\u2022 Implantaci\u00f3n de nuevas placas solares<br \/>\n\u2022 Renovaci\u00f3n de aseos del pabell\u00f3n<br \/>\n\u2022 Nuevo p\u00e1rking (octubre-noviembre)<\/p>\n<p>Si quieres obtener m\u00e1s informaci\u00f3n sobre los Campus Lauaxeta, <a href=\"https:\/\/www.lauaxeta.eus\/es\/category\/lauaxeta-campus-etorkizuna-eraikiz\/\">pincha en el siguiente enlace.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este curso los-as m\u00e1s peque\u00f1os-as han podido estrenar y disfrutar sus nuevas aulas. Dentro de las obras realizadas, hemos adaptado los espacios al proyecto pedag\u00f3gico de Educaci\u00f3n Infantil, consiguiendo un entorno m\u00e1s c\u00f3modo y transparente y conectando las aulas directamente con la zona de juego de Ikaspark. Estas obras se han desarrollado dentro del Plan [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":41927,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[229,230,1],"tags":[408,434],"class_list":["post-41926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestion","category-lauaxeta-campus-etorkizuna-eraikiz-es","category-sin-categorizar","tag-hh-es","tag-infantil"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/41926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=41926"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/41926\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/41927"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=41926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=41926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=41926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}