{"id":42359,"date":"2023-09-25T14:21:33","date_gmt":"2023-09-25T14:21:33","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=42359"},"modified":"2023-09-25T14:23:14","modified_gmt":"2023-09-25T14:23:14","slug":"que-aprendizajes-se-llevan-al-cuidar-de-las-gallinas","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/que-aprendizajes-se-llevan-al-cuidar-de-las-gallinas\/","title":{"rendered":"\u00bfQu\u00e9 aprendizajes se llevan al cuidar de las gallinas?"},"content":{"rendered":"<p><strong>Bajo el nombre de Lumalai, en Lauaxeta disponemos de un gallinero ecol\u00f3gico con gallinas que campan a sus anchas. Peri\u00f3dicamente, adem\u00e1s de cuidar a las gallinas y el gallinero, los alumnos-as se encargan de la venta de los huevos ecol\u00f3gicos. Y, \u00bfqu\u00e9 aprenden gracias a esta experiencia?<\/strong><\/p>\n<p>Un gallinero puede ser una herramienta educativa valiosa para ense\u00f1ar a los ni\u00f1os una variedad de lecciones importantes:<\/p>\n<ul>\n<li><strong>Responsabilidad:<\/strong> Cuidar de las gallinas implica una rutina diaria de alimentaci\u00f3n, agua fresca y recolecci\u00f3n de huevos. As\u00ed, aprenden a ser responsables al encargarse de estas tareas.<\/li>\n<li><strong>Conexi\u00f3n con la naturaleza<\/strong>: Pueden aprender sobre la vida en la granja y la interacci\u00f3n entre seres humanos y animales. Esto les ayuda a conectarse con la naturaleza y comprender de d\u00f3nde provienen los alimentos.<\/li>\n<li><strong>Ciclo de vida:<\/strong> Observar el ciclo de vida de las gallinas, desde la eclosi\u00f3n de los huevos hasta la vejez, brinda a los ni\u00f1os-as una comprensi\u00f3n m\u00e1s profunda de c\u00f3mo funcionan los seres vivos.<\/li>\n<li><strong>Sostenibilidad<\/strong>: Un gallinero puede ense\u00f1ar a los ni\u00f1os-as sobre la sostenibilidad, ya que pueden aprender c\u00f3mo reciclar restos de alimentos como parte de la alimentaci\u00f3n de las gallinas y c\u00f3mo las gallinas producen huevos de manera regular.<\/li>\n<li><strong>Matem\u00e1ticas y ciencias:<\/strong> Pueden estudiar conceptos matem\u00e1ticos al contar huevos, calcular cu\u00e1nta cu\u00e1nta comida necesitan las gallinas y medir el espacio del gallinero. Tambi\u00e9n pueden aprender sobre biolog\u00eda y ecolog\u00eda al observar el comportamiento de las gallinas y su relaci\u00f3n con el entorno.<\/li>\n<li><strong>Valores \u00e9ticos:<\/strong> Cuidar de las gallinas puede ayudar a los ni\u00f1os-as a desarrollar empat\u00eda hacia los animales y comprender la importancia del respeto hacia ellos y ellas.<\/li>\n<\/ul>\n<p>En general, un gallinero puede proporcionar una experiencia educativa integral, que abarca desde lecciones pr\u00e1cticas sobre la agricultura y la vida en la granja hasta valores \u00e9ticos y una mayor conciencia sobre el medio ambiente.<\/p>\n<p>Para ver parte de la experiencia, te dejamos con un video de hace unos pocos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bajo el nombre de Lumalai, en Lauaxeta disponemos de un gallinero ecol\u00f3gico con gallinas que campan a sus anchas. Peri\u00f3dicamente, adem\u00e1s de cuidar a las gallinas y el gallinero, los alumnos-as se encargan de la venta de los huevos ecol\u00f3gicos. Y, \u00bfqu\u00e9 aprenden gracias a esta experiencia? Un gallinero puede ser una herramienta educativa valiosa [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":42360,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[218,223],"tags":[408,434,458,459],"class_list":["post-42359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bertoko-es","category-ods-y-agenda-2030","tag-hh-es","tag-infantil","tag-lh-es","tag-primaria-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/42359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=42359"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/42359\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/42360"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=42359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=42359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=42359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}