{"id":42640,"date":"2023-09-29T14:16:30","date_gmt":"2023-09-29T14:16:30","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=42640"},"modified":"2023-09-30T05:48:24","modified_gmt":"2023-09-30T05:48:24","slug":"ongi-etorri-gurera","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/ongi-etorri-gurera\/","title":{"rendered":"Ongi etorri gurera!"},"content":{"rendered":"<p><strong>Son las palabras que se leen al acceder desde el parking a la ikastola y es as\u00ed como hemos recibido hoy al Consejero de Educaci\u00f3n del Gobierno Vasco Jokin Bildarratz, a la Viceconsejera de Educaci\u00f3n Bego\u00f1a Pedrosa, al Viceconsejero de Administraci\u00f3n y Servicios Xabier Aizpurua y a Maritere Ojanguren, Vice Presidenta en Consejo Escolar de Euskadi.<\/strong><\/p>\n<p>Hemos querido mostrarles una peque\u00f1a parte de lo que hacen y todo lo que saben los alumnos y alumnas, aunque Maritere lo conoce de cerca, como Directora que fue de Lauaxeta. De la mano del equipo de direcci\u00f3n y de un grupo de alumnos y alumnas han podido disfrutar de una visita guiada por las instalaciones donde los alumnos y alumnas les iban explicando los proyectos que tienen entre manos.<\/p>\n<p><strong>Aprovechamos la ocasi\u00f3n para compartiros el video de la visita y dar la bienvenida tambi\u00e9n a Lauaxeta a cualquiera que desee acercarse a conocer nuestro proyecto educativo e instalaciones.<\/strong><\/p>\n<p><strong>Ongi etorri gurera!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Son las palabras que se leen al acceder desde el parking a la ikastola y es as\u00ed como hemos recibido hoy al Consejero de Educaci\u00f3n del Gobierno Vasco Jokin Bildarratz, a la Viceconsejera de Educaci\u00f3n Bego\u00f1a Pedrosa, al Viceconsejero de Administraci\u00f3n y Servicios Xabier Aizpurua y a Maritere Ojanguren, Vice Presidenta en Consejo Escolar de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":42641,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[225,229],"tags":[],"class_list":["post-42640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conferencias-e-intervenciones","category-gestion"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/42640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=42640"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/42640\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/42641"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=42640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=42640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=42640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}