{"id":42771,"date":"2023-10-04T10:23:22","date_gmt":"2023-10-04T10:23:22","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=42771"},"modified":"2023-10-04T10:23:22","modified_gmt":"2023-10-04T10:23:22","slug":"la-comunicacion-entre-familias-e-ikastola-es-fundamental-2","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/la-comunicacion-entre-familias-e-ikastola-es-fundamental-2\/","title":{"rendered":"La comunicaci\u00f3n entre familias e ikastola es fundamental"},"content":{"rendered":"<p>Hoy en d\u00eda no es suficiente con hacer las cosas sino que es necesario informar qu\u00e9 se hace y c\u00f3mo se hace. Es una de nuestras prioridades, aunque es cierto que a veces resulta complejo, dada la amplitud de edades, proyectos e iniciativas que englobamos en la ikastola, con casi 1.500 alumnos-as de edades comprendidas entre los 12 y los 18 a\u00f1os, en la medida en que os queremos dar informaci\u00f3n relevante y algo de contexto tambi\u00e9n para que m\u00e1s all\u00e1 de la edad o etapa en la que se encuentra vuestro hijo-a pod\u00e1is tener una visi\u00f3n m\u00e1s global de la ikastola.<\/p>\n<p><strong>M\u00e1s all\u00e1 de las reuniones de inicio de curso ya celebradas, las reuniones espec\u00edficas ligadas a determinados proyectos, las entrevistas individuales o la comunicaci\u00f3n v\u00eda telef\u00f3nica o por email, el mundo digital nos ofrece m\u00faltiples oportunidades y canales de comunicaci\u00f3n con los que ya sois familia de la ikastola y con aquellas otras familias que est\u00e1n en ese periodo de reflexi\u00f3n y decisi\u00f3n sobre la matriculaci\u00f3n de su hijo-a, decisi\u00f3n de gran relevancia como padre\/ madre.<\/strong><\/p>\n<p><strong>Si quieres echar un vistazo a nuestros canales de comunicaci\u00f3n en el \u00e1mbito digital te invitamos a visitar el<a href=\"https:\/\/www.lauaxeta.eus\/es\/como-estar-al-dia-de-lo-que-ocurre-en-la-ikastola\/\" target=\"_blank\" rel=\"noopener\"> siguiente enlace.<\/a><\/strong><\/p>\n<p><strong>Si te encuentras en ese momento de decisi\u00f3n acerca de la matriculaci\u00f3n de tu hijo-a y quieres informaci\u00f3n \u00fatil, puedes inscribirte a <a href=\"https:\/\/www.lauaxeta.eus\/es\/matrikulazioak\/\" target=\"_blank\" rel=\"noopener\">nuestras jornadas de puertas abiertas.<\/a> <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy en d\u00eda no es suficiente con hacer las cosas sino que es necesario informar qu\u00e9 se hace y c\u00f3mo se hace. Es una de nuestras prioridades, aunque es cierto que a veces resulta complejo, dada la amplitud de edades, proyectos e iniciativas que englobamos en la ikastola, con casi 1.500 alumnos-as de edades comprendidas [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":42772,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-42771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escuela-de-padres"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/42771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=42771"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/42771\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/42772"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=42771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=42771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=42771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}