{"id":44181,"date":"2023-11-10T11:17:02","date_gmt":"2023-11-10T11:17:02","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=44181"},"modified":"2023-11-10T11:17:17","modified_gmt":"2023-11-10T11:17:17","slug":"saber-donde-estoy-para-poder-mejorar-la-importancia-del-feedback-en-bachillerato","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/saber-donde-estoy-para-poder-mejorar-la-importancia-del-feedback-en-bachillerato\/","title":{"rendered":"Saber d\u00f3nde estoy para poder mejorar: la Importancia del Feedback en Bachillerato"},"content":{"rendered":"<p><strong>Para poder mejorar es importante ser conscientes del punto de partida en el que os encontramos: de cu\u00e1les son nuestras fortalezas y aquellas \u00e1reas en las que tenemos margen de mejora.\u00a0 <\/strong><\/p>\n<p><strong>En este punto, m\u00e1s all\u00e1 de la percepci\u00f3n que cada uno-a podemos tener, resulta de utilidad que alguien con conocimiento y criterio nos aporte su punto de vista. Esta es la esencia del feedback, una herramienta fundamental en el desarrollo de nuestros alumnos y alumnas<\/strong>. M\u00e1s a\u00fan en el caso de Bachillerato, teniendo en cuenta la presi\u00f3n con la que viven los alumnos-as esta etapa, ante los retos a los que les tocar\u00e1 hacer frente en un futuro muy pr\u00f3ximo.<\/p>\n<p>\u00bfPor qu\u00e9 es tan vital esta comunicaci\u00f3n bidireccional entre profesores y alumnos? Acomp\u00e1\u00f1anos mientras exploramos c\u00f3mo el feedback se convierte en la br\u00fajula que gu\u00eda a nuestros j\u00f3venes hacia la mejora continua y la excelencia acad\u00e9mica.<\/p>\n<p><strong>La base de la comunicaci\u00f3n efectiva: <\/strong>Imaginemos la educaci\u00f3n como un viaje, y el feedback como el mapa que se\u00f1ala el camino. En el bachillerato, la comunicaci\u00f3n entre profesores-as y alumnos-as no solo es esencial, es la clave. Establecer un di\u00e1logo abierto y respetuoso crea un ambiente propicio para el aprendizaje y la evoluci\u00f3n constante.<\/p>\n<p><strong>Una herramienta transformadora: <\/strong>El feedback va m\u00e1s all\u00e1 de simples palabras; es una herramienta poderosa que impulsa el desarrollo de competencias y fortalece nuestro sistema de evaluaci\u00f3n. No se trata solo de decir lo que est\u00e1 bien o mal, sino de proporcionar una gu\u00eda espec\u00edfica para el crecimiento personal y acad\u00e9mico.<\/p>\n<p><strong>Feedback continuo: <\/strong>En nuestro compromiso con la mejora continua, cada alumno recibe feedback en tres momentos clave durante el curso, coincidiendo con las evaluaciones. Estos momentos no son solo puntos de control, sino oportunidades para la reflexi\u00f3n y la evoluci\u00f3n. Al comienzo, el feedback se centra en identificar y potenciar los puntos fuertes de cada estudiante. Es el momento de establecer metas y crear una base s\u00f3lida para el \u00e9xito acad\u00e9mico. En la mitad del curso, evaluamos el progreso, celebramos los logros, pero tambi\u00e9n analizamos las \u00e1reas que necesitan atenci\u00f3n. Este feedback intermedio permite a los alumnos realizar ajustes y seguir avanzando hacia la excelencia. Al finalizar el a\u00f1o, celebramos los logros obtenidos y reflexionamos sobre la experiencia. El feedback en este punto se centra en reconocer el esfuerzo, ofrecer perspectivas para el futuro y preparar a nuestros estudiantes para los desaf\u00edos venideros.<\/p>\n<p><strong>Feedback Personalizado: <\/strong>Cada estudiante es \u00fanico, y el feedback se adapta a sus necesidades individuales. No es un enfoque est\u00e1ndar; es una gu\u00eda personalizada que impulsa el crecimiento de manera significativa.<\/p>\n<p>\u00bfC\u00f3mo podemos contribuir desde casa? Apoyar este proceso en casa es fundamental. Fomentar la apertura al di\u00e1logo sobre el feedback, celebrar sus \u00e9xitos y ofrecer orientaci\u00f3n en las \u00e1reas de mejora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para poder mejorar es importante ser conscientes del punto de partida en el que os encontramos: de cu\u00e1les son nuestras fortalezas y aquellas \u00e1reas en las que tenemos margen de mejora.\u00a0 En este punto, m\u00e1s all\u00e1 de la percepci\u00f3n que cada uno-a podemos tener, resulta de utilidad que alguien con conocimiento y criterio nos aporte [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":44182,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[371,370,454,455],"class_list":["post-44181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escuela-de-padres","tag-bachillerato","tag-batxilergoa-es","tag-dbh-es","tag-eso-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/44181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=44181"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/44181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/44182"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=44181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=44181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=44181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}