{"id":44769,"date":"2023-11-29T14:37:05","date_gmt":"2023-11-29T14:37:05","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=44769"},"modified":"2023-11-29T14:37:05","modified_gmt":"2023-11-29T14:37:05","slug":"nuestra-musica-es-parte-de-nuestra-cultura","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/nuestra-musica-es-parte-de-nuestra-cultura\/","title":{"rendered":"Nuestra m\u00fasica es parte de nuestra cultura"},"content":{"rendered":"<p>Es conocida la influencia de la m\u00fasica entre los j\u00f3venes y la identificaci\u00f3n que se produce con diferentes canciones o m\u00fasicos. <strong>La m\u00fasica es un medio perfecto para acercarse a la cultura. Por ello, con el fin de difundir la transmisi\u00f3n de la cultura vasca entre los j\u00f3venes, nos hemos incorporado al programa <a href=\"https:\/\/www.nolega.euskadi.eus\/es\/musikariak-ikastetxeetan\" target=\"_blank\" rel=\"noopener\">Musikariak Ikastetxean<\/a> y hoy, alumnos de DBH4 han tenido la oportunidad de conocer <a href=\"https:\/\/liherband.com\/home\" target=\"_blank\" rel=\"noopener\">Liher<\/a>.<\/strong><br \/>\nSi quieres informaci\u00f3n, te compartimos el siguiente enlace.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es conocida la influencia de la m\u00fasica entre los j\u00f3venes y la identificaci\u00f3n que se produce con diferentes canciones o m\u00fasicos. La m\u00fasica es un medio perfecto para acercarse a la cultura. Por ello, con el fin de difundir la transmisi\u00f3n de la cultura vasca entre los j\u00f3venes, nos hemos incorporado al programa Musikariak Ikastetxean [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":44761,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[454,455],"class_list":["post-44769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-dbh-es","tag-eso-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/44769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=44769"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/44769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/44761"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=44769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=44769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=44769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}