{"id":45540,"date":"2023-12-22T10:32:08","date_gmt":"2023-12-22T10:32:08","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=45540"},"modified":"2023-12-22T10:32:08","modified_gmt":"2023-12-22T10:32:08","slug":"estudiantes-de-lauaxeta-ikastola-presentan-a-la-alcaldesa-las-ideas-con-que-participan-en-startinnova","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/estudiantes-de-lauaxeta-ikastola-presentan-a-la-alcaldesa-las-ideas-con-que-participan-en-startinnova\/","title":{"rendered":"Estudiantes de Lauaxeta Ikastola, presentan a la alcaldesa las ideas con que participan en STARTInnova"},"content":{"rendered":"<p><strong>Alumnos-as de Bachillerato de Lauaxeta presentaron en el d\u00eda de ayer, sus ideas del concurso STARTInnova a la alcaldesa de Amorebieta-Etxano Ainhoa Salterain.<\/strong><\/p>\n<p>Se trata de la und\u00e9cima edici\u00f3n de STARTInnova, <strong>otra experiencia m\u00e1s en la que el alumnado participa para demostrar y desarrollar su esp\u00edritu emprendedor<\/strong>. Ayer recibieron en el aula la visita de la alcaldesa de la localidad, Ainhoa Salterain, quien act\u00faa como su mentora.<\/p>\n<p>Te dejamos con m\u00e1s informaci\u00f3n en este <a href=\"https:\/\/www.elcorreo.com\/startinnova\/alumnado-ikastola-lauxeta-amorebietaetxano-presenta-alcaldesa-ideas-20231222093558-nt.html\">enlace.<\/a><\/p>\n<p>Aurrera!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alumnos-as de Bachillerato de Lauaxeta presentaron en el d\u00eda de ayer, sus ideas del concurso STARTInnova a la alcaldesa de Amorebieta-Etxano Ainhoa Salterain. Se trata de la und\u00e9cima edici\u00f3n de STARTInnova, otra experiencia m\u00e1s en la que el alumnado participa para demostrar y desarrollar su esp\u00edritu emprendedor. Ayer recibieron en el aula la visita de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":45541,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[371,370],"class_list":["post-45540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-bachillerato","tag-batxilergoa-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/45540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=45540"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/45540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/45541"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=45540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=45540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=45540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}