{"id":45723,"date":"2024-01-16T14:23:09","date_gmt":"2024-01-16T14:23:09","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=45723"},"modified":"2024-01-16T14:23:09","modified_gmt":"2024-01-16T14:23:09","slug":"explorando-en-emociones-y-tecnologia","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/explorando-en-emociones-y-tecnologia\/","title":{"rendered":"Explorando en emociones y tecnolog\u00eda"},"content":{"rendered":"<p>Abriendo las ventanas a lo que acontece en la ikastola, en esta ocasi\u00f3n queremos compartir con vosotros-as algo que ha acontecido en la jornada de <strong>los alumnos-as de 5\u00ba de Primaria <\/strong>y es que se han adentrado en el mundo de las emociones y de la tecnolog\u00eda.<\/p>\n<p>Lo han hecho <strong>de la mano de Sasoia<\/strong>, una colaboraci\u00f3n que valoramos enormemente aqu\u00ed en Lauaxeta Ikastola.<\/p>\n<p>Sabemos que esta etapa es emocionante y llena de descubrimientos, pero tambi\u00e9n entendemos que puede venir acompa\u00f1ada de desaf\u00edos, especialmente cuando se trata de la relaci\u00f3n de los ni\u00f1os-as con las tecnolog\u00edas digitales. La charla de hoy nos ha brindado una perspectiva valiosa sobre este tema tan relevante.<\/p>\n<p><strong>En el mundo digital actual, nuestros peque\u00f1os-as se encuentran frente a un universo de posibilidades, pero tambi\u00e9n a desaf\u00edos que pueden influir en su bienestar emocional. La charla abord\u00f3 c\u00f3mo equilibrar el uso de la tecnolog\u00eda<\/strong> para que sea una herramienta positiva en su desarrollo, fomentando la creatividad y el aprendizaje, pero tambi\u00e9n creando conciencia sobre la importancia del tiempo fuera de las pantallas.<\/p>\n<p>Adem\u00e1s, exploramos las emociones que pueden surgir en esta etapa, desde la emoci\u00f3n de aprender nuevas habilidades digitales hasta la necesidad de establecer l\u00edmites saludables. Es fundamental que como padres y educadores estemos presentes para apoyarlos en este viaje, proporcionando un espacio seguro para expresar sus emociones.<\/p>\n<p>Como siempre, os animamos a que continu\u00e9is la conversaci\u00f3n en casa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abriendo las ventanas a lo que acontece en la ikastola, en esta ocasi\u00f3n queremos compartir con vosotros-as algo que ha acontecido en la jornada de los alumnos-as de 5\u00ba de Primaria y es que se han adentrado en el mundo de las emociones y de la tecnolog\u00eda. Lo han hecho de la mano de Sasoia, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":45724,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[302,224],"tags":[458,459],"class_list":["post-45723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alianzas","category-escuela-de-padres","tag-lh-es","tag-primaria-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/45723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=45723"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/45723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/45724"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=45723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=45723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=45723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}