{"id":45913,"date":"2024-01-23T14:52:01","date_gmt":"2024-01-23T14:52:01","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=45913"},"modified":"2024-01-23T14:52:01","modified_gmt":"2024-01-23T14:52:01","slug":"sabes-cual-es-el-periodo-oficial-de-matriculaciones","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/sabes-cual-es-el-periodo-oficial-de-matriculaciones\/","title":{"rendered":"\u00bfSabes cu\u00e1l es el periodo oficial de matriculaciones?"},"content":{"rendered":"<p>Este pasado s\u00e1bado celebramos nuestra \u00faltima sesi\u00f3n de puertas abiertas. Han sido muchas las familias interesadas en conocernos y qu\u00e9 mejor manera que acercarse y verlo por uno-a mismo-a.<\/p>\n<p>Aun as\u00ed, <strong>s<\/strong><strong>abemos que decidir acerca de la matriculaci\u00f3n de tu hijo o hija es algo muy importante para ti. Tienes que valorar muchos aspectos y no resulta una tarea f\u00e1cil y por eso no queremos que te quedes con ninguna duda.<\/strong><\/p>\n<p><strong>Acumulamos mucha experiencia en el camino y puedes aprovecharla a tu favor, para ayudarte a tomar la que para ti sea la mejor decisi\u00f3n<\/strong>.<\/p>\n<p>Por eso:<\/p>\n<ul>\n<li><u>Puedes echar un vistazo a toda la informaci\u00f3n que hemos recopilado para ti<\/u> <a href=\"https:\/\/www.lauaxeta.eus\/es\/matrikulazio-prozesua-hh-lh\/\">en este enlace<\/a>.<\/li>\n<li><u>Te recordamos que puedes ponerte en contacto<\/u>, para eso te dejamos c\u00f3mo hacerlo <a href=\"https:\/\/www.lauaxeta.eus\/es\/kokapena\/\">en este enlace<\/a>.<\/li>\n<li><u>Te dejamos el enlace directo a la normativa del Gobierno Vasco<\/u> que regula el proceso de matriculaci\u00f3n <a href=\"https:\/\/www.euskadi.eus\/web01-bopv\/es\/bopv2\/datos\/2024\/01\/2400076a.shtml\">en este otro enlace<\/a>.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Este pasado s\u00e1bado celebramos nuestra \u00faltima sesi\u00f3n de puertas abiertas. Han sido muchas las familias interesadas en conocernos y qu\u00e9 mejor manera que acercarse y verlo por uno-a mismo-a. Aun as\u00ed, sabemos que decidir acerca de la matriculaci\u00f3n de tu hijo o hija es algo muy importante para ti. Tienes que valorar muchos aspectos y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":45914,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-45913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/45913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=45913"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/45913\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/45914"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=45913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=45913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=45913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}