{"id":45974,"date":"2024-01-24T10:18:38","date_gmt":"2024-01-24T10:18:38","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=45974"},"modified":"2024-01-24T10:19:09","modified_gmt":"2024-01-24T10:19:09","slug":"kirola-eta-kultura-bat-eginik","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/kirola-eta-kultura-bat-eginik\/","title":{"rendered":"Deporte y cultura: en esta ocasi\u00f3n, de la mano"},"content":{"rendered":"<p><strong>La vida no va de compartimentos estancos y el aprendizaje tampoco. Muchas veces hay actividades que generan aprendizajes diversos. El caso de hoy es m\u00e1s que evidente: en el exterior de Lauaxeta, esta ma\u00f1ana, se pod\u00eda ver a algunos-as alumnos-as de ESO, bailando el aurresku. Aunando cultura y educaci\u00f3n f\u00edsica. <\/strong>Si a la estampa le a\u00f1adimos el maravilloso verde de los montes que rodean a Lauaxeta y nuestra a veces tambi\u00e9n t\u00edpica niebla de las ma\u00f1anas, la estampa es \u201cmuy nuestra\u201d, \u00bfverdad?<\/p>\n<p>El aurresku es una danza popular vasca, revestida de solemnidad y elegancia que se baila a modo de homenaje, o reverencia, delante de personas o personalidades destacadas de la comunidad. En esta ocasi\u00f3n, as\u00ed, a modo improvisado, os lo dedicamos a todos vosotros-as.<br \/>\nAurrera!<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"LAUAXETA IKASTOLA- Gorputz hezkuntzan, Aurreskua!\" width=\"1150\" height=\"647\" src=\"https:\/\/www.youtube.com\/embed\/yo46Ix9uMak?feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/www.lauaxeta.eus\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vida no va de compartimentos estancos y el aprendizaje tampoco. Muchas veces hay actividades que generan aprendizajes diversos. El caso de hoy es m\u00e1s que evidente: en el exterior de Lauaxeta, esta ma\u00f1ana, se pod\u00eda ver a algunos-as alumnos-as de ESO, bailando el aurresku. Aunando cultura y educaci\u00f3n f\u00edsica. Si a la estampa le [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":45975,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[454,524,455,525],"class_list":["post-45974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-dbh-es","tag-educacion-fisica-es","tag-eso-es","tag-gorputz-hezkuntza-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/45974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=45974"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/45974\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/45975"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=45974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=45974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=45974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}