{"id":46099,"date":"2024-01-30T16:31:53","date_gmt":"2024-01-30T16:31:53","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=46099"},"modified":"2024-01-30T16:33:09","modified_gmt":"2024-01-30T16:33:09","slug":"hacer-que-el-deporte-sea-motivador","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/hacer-que-el-deporte-sea-motivador\/","title":{"rendered":"Hacer que un buen h\u00e1bito sea motivador"},"content":{"rendered":"<p>A pocos d\u00edas de terminar enero, puede que te hayas propuesto hacer ejercicio entre los objetivos para el nuevo a\u00f1o. Si es as\u00ed y sigues manteniendo tu buen prop\u00f3sito, <strong>sabr\u00e1s lo importante que es hacer que el ejercicio sea motivador. Al menos si queremos mantener ese prop\u00f3sito en el tiempo. A la hora de plantearlo con nuestros alumnos-as, tratamos de tenerlo tambi\u00e9n en cuenta. <\/strong>El pretender que guste a todos es quiz\u00e1s un objetivo demasiado ambicioso, pero al cambiar de estilos y actividades, al menos tenemos mayor probabilidad de dar con su gusto y motivaci\u00f3n.<\/p>\n<p><strong>La combinaci\u00f3n de ejercicio con m\u00fasica que nos guste es una buena alianza por ejemplo<\/strong>. Hoy precisamente, <strong>hemos podido ver a algunos alumnos-as de ESO bailando juna coreograf\u00eda de aerobic al ritmo de la m\u00fasica<\/strong>. Coordinaci\u00f3n, ritmo y el ejercicio cardiovascular. Aurrera!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pocos d\u00edas de terminar enero, puede que te hayas propuesto hacer ejercicio entre los objetivos para el nuevo a\u00f1o. Si es as\u00ed y sigues manteniendo tu buen prop\u00f3sito, sabr\u00e1s lo importante que es hacer que el ejercicio sea motivador. Al menos si queremos mantener ese prop\u00f3sito en el tiempo. A la hora de plantearlo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":46097,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[454,524,455,525],"class_list":["post-46099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-dbh-es","tag-educacion-fisica-es","tag-eso-es","tag-gorputz-hezkuntza-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/46099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=46099"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/46099\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/46097"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=46099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=46099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=46099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}