{"id":46169,"date":"2024-02-05T10:09:17","date_gmt":"2024-02-05T10:09:17","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=46169"},"modified":"2024-02-05T10:32:22","modified_gmt":"2024-02-05T10:32:22","slug":"de-parte-de-los-ninos-as-de-4-anos-felicidad-a-todas-las-familias","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/de-parte-de-los-ninos-as-de-4-anos-felicidad-a-todas-las-familias\/","title":{"rendered":"De parte de los ni\u00f1os-as de 4 a\u00f1os\u2026 \u00a1felicidad a todas las familias!"},"content":{"rendered":"<p>\u201cSanta Ageda bezpera dugu\u2026 Euskal Herriko eguna. etxe honetan zorion hutsa betiko euko al dabe.\u201d Es como dice la canci\u00f3n que cada a\u00f1o se canta en v\u00edspera de Santa Agueda y desea felicidad en las familias. <strong>Hoy los alumnos-as de 4 a\u00f1os nos han cantado en Lauaxeta y de su parte os deseamos felicidad a todas las casas y todas las familias.<\/strong><\/p>\n<p>Os dejamos con el video de los artistas del d\u00eda de hoy.<\/p>\n<p>Ongi izan eta besarkada bana!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSanta Ageda bezpera dugu\u2026 Euskal Herriko eguna. etxe honetan zorion hutsa betiko euko al dabe.\u201d Es como dice la canci\u00f3n que cada a\u00f1o se canta en v\u00edspera de Santa Agueda y desea felicidad en las familias. Hoy los alumnos-as de 4 a\u00f1os nos han cantado en Lauaxeta y de su parte os deseamos felicidad a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":46170,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[220],"tags":[408,434],"class_list":["post-46169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos-y-celebraciones","tag-hh-es","tag-infantil"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/46169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=46169"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/46169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/46170"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=46169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=46169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=46169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}