{"id":46728,"date":"2024-02-27T09:21:36","date_gmt":"2024-02-27T09:21:36","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=46728"},"modified":"2024-02-27T09:23:10","modified_gmt":"2024-02-27T09:23:10","slug":"descubre-todo-lo-que-tenemos-preparado-para-ti-este-verano","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/descubre-todo-lo-que-tenemos-preparado-para-ti-este-verano\/","title":{"rendered":"\u00a1Descubre todo lo que tenemos preparado para ti este verano!"},"content":{"rendered":"<p>Llegan las merecidas vacaciones para nuestros hijos-as pero a\u00fan hay que esperar para las tambi\u00e9n merecidas vacaciones de aita y ama. Es una realidad que en ocasiones trae bastantes quebraderos de cabeza. \u00bfQu\u00e9 hacer?<\/p>\n<p><strong>En Lauaxeta, tratamos de ofrecer una amplia variedad de actividades de verano que respondan a los intereses de las diferentes edades y etapas de nuestros hijos-as y alumnos-as. <\/strong><\/p>\n<p><strong>Para los m\u00e1s txikis, tenemos los Udaleku irekiak<\/strong>, con actividades l\u00fadicas en la propia ikastola. Nuestro monitorado est\u00e1 preparado para brindar un ambiente seguro y divertido donde tus hijos e hijas puedan explorar su creatividad, fomentar el juego y aprender mientras se divierten.<\/p>\n<p><strong>Para los-as de 3\u00ba y 4\u00ba de Primaria tenemos la posibilidad de tomar parte en un campus de Bilbao Basket y los de 5\u00ba y 6\u00ba podr\u00e1n elegir entre skate o vela<\/strong>.<\/p>\n<p><strong>Para los m\u00e1s aventureros-as, nuestros campamentos en lugares como Lizarra y Egino <\/strong>ofrecen la oportunidad perfecta para realizar su primera estancia fuera de casa, sumergirse en la naturaleza, hacer nuevos amigos y disfrutar de una variedad de actividades emocionantes.<\/p>\n<p><strong>En el caso de Secundaria<\/strong>, para que descarguen toda la energ\u00eda que les caracteriza con <strong>actividades que les resulten atractivas, hemos pensado en skate, vela y excursiones por el monte<\/strong>. Estas actividades son perfectas para aquellos que desean probar algo nuevo, desarrollar habilidades nuevas y crear recuerdos duraderos con amigos y compa\u00f1eros de clase.<\/p>\n<p><strong>Adem\u00e1s, en el caso de Bachillerato, para quien desee aprovechar al m\u00e1ximo el verano, ofrecemos la posibilidad de prepararse para obtener t\u00edtulos de euskara o de monitor de tiempo libre<\/strong>. Estas oportunidades brindan una excelente manera de mejorar tus habilidades ling\u00fc\u00edsticas o adquirir experiencia pr\u00e1ctica mientras te diviertes y conoces nuevas personas, \u00a1sumando en positivo para su futuro!<\/p>\n<p>En definitiva, experiencias inolvidables para todas las edades que combinan aprendizaje y diversi\u00f3n.<\/p>\n<p>Puedes echar un vistazo en el siguiente <a href=\"https:\/\/www.lauaxeta.eus\/es\/udako-jarduerak\/\">enlace.<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Llegan las merecidas vacaciones para nuestros hijos-as pero a\u00fan hay que esperar para las tambi\u00e9n merecidas vacaciones de aita y ama. Es una realidad que en ocasiones trae bastantes quebraderos de cabeza. \u00bfQu\u00e9 hacer? En Lauaxeta, tratamos de ofrecer una amplia variedad de actividades de verano que respondan a los intereses de las diferentes edades [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":46765,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[221],"tags":[],"class_list":["post-46728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-extraescolares-y-de-verano"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/46728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=46728"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/46728\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/46765"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=46728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=46728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=46728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}