{"id":47472,"date":"2024-03-13T08:29:37","date_gmt":"2024-03-13T08:29:37","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=47472"},"modified":"2024-03-13T08:35:41","modified_gmt":"2024-03-13T08:35:41","slug":"lauaxeta-y-athletic-non-league-day-participa-y-gana","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/lauaxeta-y-athletic-non-league-day-participa-y-gana\/","title":{"rendered":"Lauaxeta y Athletic Non League Day: \u00a1participa y gana!"},"content":{"rendered":"<p><strong>Como club convenido del Athletic y con el objetivo de visibilizar nuestro f\u00fatbol, se ha puesto en marcha el Non League day, con el objetivo de destacar la importancia del f\u00fatbol base y a fomentar la asistencia a los campos locales. Para ello el Athletic Club celebra el 23 y 24 de marzo la fiesta anual del f\u00fatbol base y organiza un programa lleno de alicientes para los clubes convenidos y aficiones locales. Entre ellos, dos sorteos:<\/strong><\/p>\n<p><u>El de las RRSS.<\/u> Si te animas a participar tienes que sacarte una foto el d\u00eda 23 en el partido y publicarlas en vuestras redes sociales con el hashtag #EuskalNonLeagueDay y #LauaxetaIkastola. Los premios a los que puedes optar son una camiseta firmada por el equipo masculino, otra firmada por el equipo femenino y dos entradas para un partido de la liga en San Mam\u00e9s.<\/p>\n<p><u>El del\u00a0 boleto de 3\u20ac:<\/u> al comprar la participaci\u00f3n de 3\u20ac se entra autom\u00e1ticamente en el sorteo de los siguientes premios: entrada doble para 2 personas, viaje y estancia en un partido de la liga fuera de San Mam\u00e9s; entrada doble Lions experience con localidad VIP y encuentro con los jugadores y entrada doble Lions experience.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-47476\" src=\"https:\/\/www.lauaxeta.eus\/wp-content\/uploads\/2024\/03\/MAITANEK-AGINTZEKO-RRSSSORTEO-1080x1080-1-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.lauaxeta.eus\/wp-content\/uploads\/2024\/03\/MAITANEK-AGINTZEKO-RRSSSORTEO-1080x1080-1-300x300.jpg 300w, https:\/\/www.lauaxeta.eus\/wp-content\/uploads\/2024\/03\/MAITANEK-AGINTZEKO-RRSSSORTEO-1080x1080-1-1024x1024.jpg 1024w, https:\/\/www.lauaxeta.eus\/wp-content\/uploads\/2024\/03\/MAITANEK-AGINTZEKO-RRSSSORTEO-1080x1080-1-150x150.jpg 150w, https:\/\/www.lauaxeta.eus\/wp-content\/uploads\/2024\/03\/MAITANEK-AGINTZEKO-RRSSSORTEO-1080x1080-1-768x768.jpg 768w, https:\/\/www.lauaxeta.eus\/wp-content\/uploads\/2024\/03\/MAITANEK-AGINTZEKO-RRSSSORTEO-1080x1080-1-600x600.jpg 600w, https:\/\/www.lauaxeta.eus\/wp-content\/uploads\/2024\/03\/MAITANEK-AGINTZEKO-RRSSSORTEO-1080x1080-1.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<div style=\"width: 1080px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-47472-1\" width=\"1080\" height=\"1080\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/www.lauaxeta.eus\/wp-content\/uploads\/2024\/03\/EUSKAL-NON-LEAGUE-DAY-ZOZKETA-1080-x-108.mp4?_=1\" \/><a href=\"https:\/\/www.lauaxeta.eus\/wp-content\/uploads\/2024\/03\/EUSKAL-NON-LEAGUE-DAY-ZOZKETA-1080-x-108.mp4\">https:\/\/www.lauaxeta.eus\/wp-content\/uploads\/2024\/03\/EUSKAL-NON-LEAGUE-DAY-ZOZKETA-1080-x-108.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Como club convenido del Athletic y con el objetivo de visibilizar nuestro f\u00fatbol, se ha puesto en marcha el Non League day, con el objetivo de destacar la importancia del f\u00fatbol base y a fomentar la asistencia a los campos locales. Para ello el Athletic Club celebra el 23 y 24 de marzo la fiesta [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":47476,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[221,302],"tags":[],"class_list":["post-47472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-extraescolares-y-de-verano","category-alianzas"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/47472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=47472"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/47472\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/47476"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=47472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=47472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=47472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}