{"id":47939,"date":"2024-03-22T10:26:41","date_gmt":"2024-03-22T10:26:41","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=47939"},"modified":"2024-03-22T11:14:08","modified_gmt":"2024-03-22T11:14:08","slug":"korrika-korrika-txiki","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/korrika-korrika-txiki\/","title":{"rendered":"\u00a1Hoy adem\u00e1s de Korrika, Korrika txiki!"},"content":{"rendered":"<p><strong>Esta tarde a las 18:23 exactamente Lauaxeta tomar\u00e1 el testigo en la Korrika.<\/strong> Previamente, desde las 16:30 tendremos m\u00fasica y chocolate en la ikastola para amenizar, celebrar y unirnos juntos luego a la Korrika.<\/p>\n<p><strong>Pero adem\u00e1s, esta ma\u00f1ana, en Lauaxeta hemos celebrado nuestro Korrika Txiki.<\/strong><\/p>\n<p>Si quieres ver esta y otras iniciativas de Lauaxeta en favor del euskara puedes hacerlo pinchando <a href=\"https:\/\/www.lauaxeta.eus\/eu\/tag\/euskara\/\">en este enlace.<\/a><\/p>\n<p>Aurrera, guztiona da eta!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta tarde a las 18:23 exactamente Lauaxeta tomar\u00e1 el testigo en la Korrika. Previamente, desde las 16:30 tendremos m\u00fasica y chocolate en la ikastola para amenizar, celebrar y unirnos juntos luego a la Korrika. Pero adem\u00e1s, esta ma\u00f1ana, en Lauaxeta hemos celebrado nuestro Korrika Txiki. Si quieres ver esta y otras iniciativas de Lauaxeta en [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":47940,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[201],"class_list":["post-47939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-euskara-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/47939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=47939"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/47939\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/47940"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=47939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=47939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=47939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}