{"id":48017,"date":"2024-04-10T12:41:42","date_gmt":"2024-04-10T12:41:42","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=48017"},"modified":"2024-04-10T12:42:03","modified_gmt":"2024-04-10T12:42:03","slug":"el-trabajo-el-servicio-y-la-seguridad-son-nuestra-prioridad","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/el-trabajo-el-servicio-y-la-seguridad-son-nuestra-prioridad\/","title":{"rendered":"El trabajo, el servicio y la seguridad, son nuestra prioridad"},"content":{"rendered":"<p><strong>En un d\u00eda especial como el de ma\u00f1ana, en el que se celebra el logro del Athletic<\/strong>, los medios han querido hacerse eco de c\u00f3mo se afronta la jornada desde las ikastolas y para ello se acercaron a Lauaxeta en el d\u00eda de ayer.<\/p>\n<p>En ese sentido, <strong>nuestras prioridades son el trabajo, el servicio educativo y la seguridad<\/strong>:<\/p>\n<p>&#8211;<strong>El servicio educativo que prestamos a las familias y a los alumnos-as y a los-as que nos debemos<\/strong>: siendo as\u00ed, el d\u00eda de ma\u00f1ana es para nosotros-as una jornada lectiva, manteniendo las clases escolares y extraescolares, entendiendo la no asistencia como una ausencia a justificar.<\/p>\n<p>&#8211;<strong>La seguridad que ante todo queremos para los-as alumnos-as y las familias<\/strong>: por lo que entendiendo las limitaciones log\u00edsticas relacionadas con el tr\u00e1fico en Bilbao, los autobuses afectados saldr\u00e1n del centro a la 13:00 y aquellas familias que deseen que sus hijos-as salgan antes de clase, lo har\u00e1n a las 12:00.<\/p>\n<p><strong>Los grandes logros no se obtienen de la noche a la ma\u00f1ana, son el resultado del trabajo y la dedicaci\u00f3n. As\u00ed es en el caso del triunfo que venimos celebrando estos d\u00edas, y lo es y ser\u00e1 as\u00ed en el caso de los triunfos que seguro cosechar\u00e1n nuestros-as alumnos-as. Es el mensaje que queremos transmitir a familias y alumnos-as, ofreciendo el servicio con el que estamos comprometidos y haci\u00e9ndoles ver que es compatible celebrar los logros y cumplir en lo individual, cada cual, con sus compromisos y obligaciones.<\/strong><\/p>\n<p>Te dejamos con el enlace a la noticia publicada en Gaur Egun y Teleberri.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un d\u00eda especial como el de ma\u00f1ana, en el que se celebra el logro del Athletic, los medios han querido hacerse eco de c\u00f3mo se afronta la jornada desde las ikastolas y para ello se acercaron a Lauaxeta en el d\u00eda de ayer. En ese sentido, nuestras prioridades son el trabajo, el servicio educativo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":48018,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[234],"tags":[],"class_list":["post-48017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avisos"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/48017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=48017"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/48017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/48018"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=48017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=48017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=48017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}