{"id":48034,"date":"2024-04-11T10:07:21","date_gmt":"2024-04-11T10:07:21","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=48034"},"modified":"2024-04-11T10:07:21","modified_gmt":"2024-04-11T10:07:21","slug":"cuidando-a-los-animales-y-su-espacio","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/cuidando-a-los-animales-y-su-espacio\/","title":{"rendered":"Cuidando a los animales y su espacio"},"content":{"rendered":"<p><strong>Los animales de la Lauaxeta Ikastola est\u00e1n atendidos tambi\u00e9n en vacaciones pero tras la vuelta de vacaciones de los alumnos-as ha sido el momento de que los alumnos-as vuelvan a visitarles y cuidar de ellos. De hecho, cuidar de los animales puede ser una experiencia muy enriquecedora para los ni\u00f1os-as. Algunas de las cosas que pueden aprender incluyen:<\/strong><\/p>\n<ul>\n<li><strong><u>Responsabilidad:<\/u><\/strong> Al encargarse de los cuidados de un animal, como alimentarlo, darle agua, y limpiar su espacio, aprenden sobre la importancia de cumplir con responsabilidades.<\/li>\n<li><strong><u>Empat\u00eda<\/u><\/strong>: Cuidar de un animal les permite entender las necesidades y los sentimientos de otros seres vivos, fomentando la empat\u00eda y la compasi\u00f3n.<\/li>\n<li><strong><u>Respeto<\/u><\/strong>: Aprenden a respetar a los animales como seres vivos con necesidades y deseos propios, lo que puede llevar a un comportamiento m\u00e1s respetuoso hacia los dem\u00e1s seres vivos y el medio ambiente en general.<\/li>\n<li><strong><u>Observaci\u00f3n<\/u><\/strong>: Cuidar de los animales tambi\u00e9n implica observar su comportamiento y sus necesidades, lo que puede ayudar a desarrollar habilidades de observaci\u00f3n y comprensi\u00f3n del mundo natural.<\/li>\n<li><strong><u>Apreciaci\u00f3n de la naturaleza<\/u><\/strong>: Al interactuar de cerca con los animales, pueden desarrollar un mayor aprecio por la naturaleza y la diversidad de formas de vida en nuestro planeta.<\/li>\n<\/ul>\n<p>En resumen, cuidar de los animales puede ser una experiencia educativa que ense\u00f1a valores importantes como la responsabilidad, la empat\u00eda y el respeto hacia los dem\u00e1s seres vivos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los animales de la Lauaxeta Ikastola est\u00e1n atendidos tambi\u00e9n en vacaciones pero tras la vuelta de vacaciones de los alumnos-as ha sido el momento de que los alumnos-as vuelvan a visitarles y cuidar de ellos. De hecho, cuidar de los animales puede ser una experiencia muy enriquecedora para los ni\u00f1os-as. Algunas de las cosas que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":48035,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[620,208],"class_list":["post-48034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-eskola-ortua-es","tag-huerto-escolar"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/48034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=48034"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/48034\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/48035"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=48034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=48034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=48034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}