{"id":48103,"date":"2024-04-16T15:29:29","date_gmt":"2024-04-16T15:29:29","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=48103"},"modified":"2024-04-16T15:29:29","modified_gmt":"2024-04-16T15:29:29","slug":"una-leccion-teatral-sobre-el-medioambiente","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/una-leccion-teatral-sobre-el-medioambiente\/","title":{"rendered":"Una lecci\u00f3n teatral sobre el medioambiente"},"content":{"rendered":"<p><strong>\u00a1Hoy ha sido un d\u00eda emocionante para los alumnos-as de 4\u00ba de primaria de nuestra ikastola! Han tenido la oportunidad \u00fanica de sumergirse en el mundo del teatro sin siquiera tener que salir de nuestro centro. \u00bfC\u00f3mo es posible? Bueno, la compa\u00f1\u00eda de teatro <a href=\"https:\/\/www.markeline.com\/eu\/\" target=\"_blank\" rel=\"noopener\">Markeli\u00f1e<\/a> ha tra\u00eddo toda la magia del escenario directamente a nosotros-as.<\/strong><\/p>\n<p>En esta ocasi\u00f3n, la obra de teatro ten\u00eda un tema muy especial: el medioambiente. A trav\u00e9s de actuaciones cautivadoras, di\u00e1logos inspiradores y escenograf\u00edas atractivas, nuestros estudiantes se han embarcado en un viaje educativo sobre la importancia de cuidar nuestro planeta.<\/p>\n<p>Adem\u00e1s les ha brindado una experiencia cultural enriquecedora, ya que el teatro es una forma de arte que estimula la creatividad y la expresi\u00f3n personal.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Hoy ha sido un d\u00eda emocionante para los alumnos-as de 4\u00ba de primaria de nuestra ikastola! Han tenido la oportunidad \u00fanica de sumergirse en el mundo del teatro sin siquiera tener que salir de nuestro centro. \u00bfC\u00f3mo es posible? Bueno, la compa\u00f1\u00eda de teatro Markeli\u00f1e ha tra\u00eddo toda la magia del escenario directamente a nosotros-as. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":48104,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[302],"tags":[458,459],"class_list":["post-48103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alianzas","tag-lh-es","tag-primaria-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/48103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=48103"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/48103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/48104"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=48103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=48103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=48103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}