{"id":48507,"date":"2024-05-07T14:04:29","date_gmt":"2024-05-07T14:04:29","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=48507"},"modified":"2024-05-07T14:11:01","modified_gmt":"2024-05-07T14:11:01","slug":"expertia-las-familias-teneis-mucho-que-ensenar","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/expertia-las-familias-teneis-mucho-que-ensenar\/","title":{"rendered":"Expertia: \u00a1las familias ten\u00e9is mucho que aportar!"},"content":{"rendered":"<p><strong>Ho<\/strong><strong>y <\/strong><strong>queremos hablaros sobre un programa que hace que nuestra ikastola sea un espacio verdaderamente abierto y enriquecedor: el programa Expertia. Si a\u00fan no lo conoces, Expertia es mucho m\u00e1s que una serie de charlas o conferencias; es un punto de encuentro donde diferentes expertos y expertas comparten sus conocimientos y experiencias con nuestros alumnos y alumnas.<\/strong><\/p>\n<p><strong>En el d\u00eda de hoy, Ir\u00eda, la amatxu de Nile, vali\u00e9ndose de su experiencia profesional ha venido a hablar a los ni\u00f1\u00f3s-as acerca del dinero.<\/strong><\/p>\n<p>Profesionales de diferentes \u00e1reas visitan nuestras aulas para compartir sus trayectorias, sus desaf\u00edos y sus logros. Esto es precisamente lo que ofrece Expertia.\u00a0<strong>A lo largo del curso escolar, m\u00faltiples agentes sociales se acercan a nuestras aulas para participar en este programa, aportando su granito de arena a la educaci\u00f3n de nuestros estudiantes.<\/strong><\/p>\n<p>\u00bfQu\u00e9 es lo que hace tan especial a Expertia? En primer lugar, su enfoque en la experiencia personal como fuente de aprendizaje.\u00a0<strong>Cada sesi\u00f3n es una oportunidad \u00fanica para que nuestros alumnos y alumnas se sumerjan en historias reales, en vivencias aut\u00e9nticas que les permiten entender el mundo de una manera m\u00e1s profunda y significativa.<\/strong><\/p>\n<p>Los objetivos de Expertia son claros: mejorar las competencias del alumnado y enriquecer su visi\u00f3n sobre el mundo que les rodea. \u00bfC\u00f3mo lo logramos? Gracias a la participaci\u00f3n activa de familias, exalumnos-as y profesionales externos, quienes comparten sus conocimientos t\u00e9cnicos y profesionales con nuestra comunidad educativa.<\/p>\n<p>Seguro que t\u00fa tambi\u00e9n tienes mucho que aportar. \u00bfTe animas? Te dejamos m\u00e1s\u00a0<a href=\"https:\/\/www.lauaxeta.eus\/es\/expertia\/\">aqu\u00ed.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy queremos hablaros sobre un programa que hace que nuestra ikastola sea un espacio verdaderamente abierto y enriquecedor: el programa Expertia. Si a\u00fan no lo conoces, Expertia es mucho m\u00e1s que una serie de charlas o conferencias; es un punto de encuentro donde diferentes expertos y expertas comparten sus conocimientos y experiencias con nuestros alumnos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":48517,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[210,458,459],"class_list":["post-48507","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-expertia-es","tag-lh-es","tag-primaria-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/48507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=48507"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/48507\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/48517"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=48507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=48507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=48507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}