{"id":48637,"date":"2024-05-10T10:30:46","date_gmt":"2024-05-10T10:30:46","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=48637"},"modified":"2024-05-10T10:30:46","modified_gmt":"2024-05-10T10:30:46","slug":"euskaraz-biziz-abestuz-eta-mintzatuz","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/euskaraz-biziz-abestuz-eta-mintzatuz\/","title":{"rendered":"Euskaraz biziz, abestuz eta mintzatuz!"},"content":{"rendered":"<p><strong>La m\u00fasica siempre tiene ese poder especial de despertarnos emociones profundas. Si adem\u00e1s cantamos en nuestra lengua, en nuestro idioma, y revivimos canciones propias de nuestra cultura lo que experimentamos va m\u00e1s all\u00e1 de la alegr\u00eda; es como un abrazo c\u00e1lido que de alguna manera nos reconforta el alma.<\/strong><\/p>\n<p>Ayer, en la ikastola, tuvimos la suerte de contar con Inun, un antiguo alumno que nos regal\u00f3 una tarde inolvidable con su guitarra y su voz.<\/p>\n<p><strong>Si a\u00f1adimos a la escena un tiempo y luz primaveral, un mont\u00f3n de \u00e1rboles rebosantes de hojas que bailaban con el viento y alumnos y alumnas que se agarraban del hombro para corear las canciones, podemos decir que casi seguro el d\u00eda de ayer perdurar\u00e1 en su recuerdo por mucho tiempo.<\/strong><\/p>\n<p>Es importante valorar y celebrar estas experiencias que nos conectan con nuestras ra\u00edces, que nos hacen sentir parte de algo m\u00e1s grande que nosotros-as mismos-as. <strong>Vincular emocionalmente el euskara con momentos y emociones positivas<\/strong>.<\/p>\n<p>Euskaraz biziz, abestuz eta mintzatuz!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La m\u00fasica siempre tiene ese poder especial de despertarnos emociones profundas. Si adem\u00e1s cantamos en nuestra lengua, en nuestro idioma, y revivimos canciones propias de nuestra cultura lo que experimentamos va m\u00e1s all\u00e1 de la alegr\u00eda; es como un abrazo c\u00e1lido que de alguna manera nos reconforta el alma. Ayer, en la ikastola, tuvimos la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":48638,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[201,458,459],"class_list":["post-48637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-euskara-es","tag-lh-es","tag-primaria-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/48637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=48637"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/48637\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/48638"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=48637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=48637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=48637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}