{"id":49131,"date":"2024-05-24T10:44:40","date_gmt":"2024-05-24T08:44:40","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=49131"},"modified":"2024-05-24T10:44:40","modified_gmt":"2024-05-24T08:44:40","slug":"conocimientos-ajenos-que-inspiran","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/conocimientos-ajenos-que-inspiran\/","title":{"rendered":"Conocimientos ajenos que inspiran"},"content":{"rendered":"<p><strong>Alumnos-as de 4\u00ba de ESO de Lauaxeta han participado en el programa Jakin-mina de Jakiunde.<\/strong><\/p>\n<p><strong>Gracias a ello, tienen la oportunidad de recibir conferencias de expertos-as de alto nivel de diferentes \u00e1mbitos y aprender de ellos-as.<\/strong><\/p>\n<p>Zorionak guztioi: Mirari Aranguren, Ane Bilbao, Leire Ibarra, Ane Marin, Igor Murga, Ane Gorro\u00f1o, Markel Noriega y Aimar Olalde<br \/>\nEste programa cuenta con el apoyo del Gobiernos Vasco, Gobierno de Navarra y la colaboraci\u00f3n de entidades como la Fundaci\u00f3n Kutxa, la Universidad de Deusto, la Universidad del Pa\u00eds Vasco, Mondragon Unibertsitatea, la Universidad de Navarra, la Universidad p\u00fablica de Navarra y Polymat.<\/p>\n<p>M\u00e1s informaci\u00f3n en el <a href=\"https:\/\/www.jakiunde.eus\/es\/noticia\/abiertas-inscripciones-jakin-mina-2023-2024\" target=\"_blank\" rel=\"noopener\">siguiente enlace.<\/a><\/p>\n<p>Aurrera!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alumnos-as de 4\u00ba de ESO de Lauaxeta han participado en el programa Jakin-mina de Jakiunde. Gracias a ello, tienen la oportunidad de recibir conferencias de expertos-as de alto nivel de diferentes \u00e1mbitos y aprender de ellos-as. Zorionak guztioi: Mirari Aranguren, Ane Bilbao, Leire Ibarra, Ane Marin, Igor Murga, Ane Gorro\u00f1o, Markel Noriega y Aimar Olalde [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":49132,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[236],"tags":[454,455],"class_list":["post-49131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-premios-y-reconocimientos","tag-dbh-es","tag-eso-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/49131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=49131"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/49131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/49132"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=49131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=49131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=49131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}