{"id":49312,"date":"2024-05-31T10:26:04","date_gmt":"2024-05-31T08:26:04","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/la-metamorfosis-un-proyecto-sobre-el-desarrollo-personal\/"},"modified":"2024-05-31T10:33:18","modified_gmt":"2024-05-31T08:33:18","slug":"la-metamorfosis-un-proyecto-sobre-el-desarrollo-personal","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/la-metamorfosis-un-proyecto-sobre-el-desarrollo-personal\/","title":{"rendered":"La metamorfosis: un proyecto sobre el desarrollo personal"},"content":{"rendered":"<p><strong>Queremos compartir con vosotros un proyecto emocionante en el que se encuentran inmersos-as algunos-as alumnos-as de 5 a\u00f1os. En el aula, tienen unas cris\u00e1lidas y orugas que est\u00e1n a punto de transformarse en mariposas. Ahora, toca esperar pacientemente y observar c\u00f3mo crecen y se desarrollan estos peque\u00f1os seres.<\/strong><\/p>\n<p>Este proyecto es una oportunidad fant\u00e1stica para aprendan sobre el ciclo de la vida de las mariposas de una manera directa y muy visual. A trav\u00e9s de la observaci\u00f3n diaria, est\u00e1n entendiendo conceptos importantes como la metamorfosis, el crecimiento y el cambio. Adem\u00e1s, este proceso les ense\u00f1a a ser pacientes y cuidadosos-as, ya que deben esperar el tiempo necesario y cuidar de las cris\u00e1lidas con mucho mimo.<\/p>\n<p>Pero este proyecto no solo trata sobre mariposas. De alguna manera, la metamorfosis que estamos presenciando en clase es una met\u00e1fora del propio desarrollo de nuestros alumnos y alumnas. Al igual que las cris\u00e1lidas se transforman en mariposas, nuestros peque\u00f1os-as tambi\u00e9n est\u00e1n en un proceso de cambio y crecimiento constante. Cada d\u00eda que pasa, aprenden cosas nuevas, desarrollan sus habilidades y se preparan para desplegar sus propias alas en el futuro.<\/p>\n<p>Es un placer ver c\u00f3mo se emocionan con cada peque\u00f1o cambio que observan y c\u00f3mo esto les inspira a seguir descubriendo y aprendiendo.<\/p>\n<p>Os mantendremos informados-as sobre el progreso de nuestras mariposas, as\u00ed como de los pollitos. Puedes leer acerca de este otro proyecto <a href=\"https:\/\/www.lauaxeta.eus\/es\/puede-nacer-un-pollito-de-un-huevo-del-super\/\">en este enlace.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Queremos compartir con vosotros un proyecto emocionante en el que se encuentran inmersos-as algunos-as alumnos-as de 5 a\u00f1os. En el aula, tienen unas cris\u00e1lidas y orugas que est\u00e1n a punto de transformarse en mariposas. Ahora, toca esperar pacientemente y observar c\u00f3mo crecen y se desarrollan estos peque\u00f1os seres. Este proyecto es una oportunidad fant\u00e1stica para [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":49307,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[408,434],"class_list":["post-49312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-hh-es","tag-infantil"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/49312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=49312"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/49312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/49307"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=49312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=49312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=49312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}