{"id":49528,"date":"2024-06-12T12:28:13","date_gmt":"2024-06-12T10:28:13","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=49528"},"modified":"2024-06-12T12:28:13","modified_gmt":"2024-06-12T10:28:13","slug":"tres-alumnas-de-lauaxeta-silver-cum-laude","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/tres-alumnas-de-lauaxeta-silver-cum-laude\/","title":{"rendered":"Tres alumnas de Lauaxeta, \u00a1Silver Cum Laude!"},"content":{"rendered":"<p>Los Objetivos de Desarrollo Sostenible son un marco de referencia en nuestras experiencias de aprendizaje. Presentar a nuestro alumnado a experiencias externas que les permitan poner en valor todo lo que saben y de lo que son capaces, como fuente a su vez de nuevos aprendizajes es tambi\u00e9n algo que favorecemos.<\/p>\n<p>The Challenge\u00a0es una oportunidad precisamente para impulsar el talento y convertir al alumnado en j\u00f3venes con compromiso hacia los retos del siglo XXI.<\/p>\n<p><strong>Alumnas y alumnos de ESO han participado este a\u00f1o en una nueva edici\u00f3n de esta experiencia. <a href=\"https:\/\/www.lauaxeta.eus\/es\/tres-alumnos-as-de-lauaxeta-iran-a-berlin-a-presentar-su-proyecto-en-el-certamen-europeo-de-emprendimiento-juvenil-youth-start\/https:\/www.youthstart.network\/events-1\">Algunas obtuvieron el paso al certamen Europeo de Emprendimiento Juvenil\u00a0Youth Start<\/a><\/strong><strong>, <\/strong><strong>para presentar sus proyectos.<\/strong><\/p>\n<p><strong>Otras, como es el caso de Leire Gauna, Eider Carrasco y Ziortza Toledano, han obtenido el reconocimiento Silver Cum Laude, por su dedicaci\u00f3n y buen trabajo<\/strong>. Zorionak!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Objetivos de Desarrollo Sostenible son un marco de referencia en nuestras experiencias de aprendizaje. Presentar a nuestro alumnado a experiencias externas que les permitan poner en valor todo lo que saben y de lo que son capaces, como fuente a su vez de nuevos aprendizajes es tambi\u00e9n algo que favorecemos. The Challenge\u00a0es una oportunidad [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":49529,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[236],"tags":[454,455],"class_list":["post-49528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-premios-y-reconocimientos","tag-dbh-es","tag-eso-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/49528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=49528"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/49528\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/49529"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=49528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=49528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=49528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}